{"id":15873,"date":"2019-03-01T13:09:51","date_gmt":"2019-03-01T12:09:51","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15873"},"modified":"2019-02-26T08:07:33","modified_gmt":"2019-02-26T07:07:33","slug":"pollo-agro-dolce","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/03\/01\/pollo-agro-dolce\/","title":{"rendered":"Pollo agro-dolce con &#8220;Lien Ying &#8211; Wok-W\u00c3\u00bcrfel&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Ogni tanto Tobias resta a scuola a mangiare anche il giovedi quando, a ben vedere, non avrebbe nessuna lezione nel pomeriggio.<\/p>\n<p>Ma oggi ha deciso di arrivare a casa in orario.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Che fare?<br \/>\nCosa preparare per tutti?<\/p>\n<p style=\"text-align: justify;\">Avevo dei petti di pollo in frigo, cosi&#8217; ho pensato di preparare qualche cosa pseudo-cinese, anche perche&#8217; abbiamo appena finito di festeggiarne il Capodanno (anno del Maiale\/Cinghiale).<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217;, giusto per proseguire con i festeggiamenti, ho preso in mano il mio Wok e mi sono dedicata a tagliuzzare il pollo a pezzetti.<\/p>\n<figure id=\"attachment_15874\" aria-describedby=\"caption-attachment-15874\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15874\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125730-e1549543624118-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15874\" class=\"wp-caption-text\">Lien Ying &#8211; Wok-W\u00c3\u00bcrfel<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In dispensa ho poi trovato questo dado &#8220;Wok&#8221; indicato per la cucina asiatica, cosi&#8217; da donare un sapore dolce-agro alla pietanza in preparazione.<\/p>\n<figure id=\"attachment_15875\" aria-describedby=\"caption-attachment-15875\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15875\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_125756-e1549543613461-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15875\" class=\"wp-caption-text\">Lien Ying &#8211; Wok-W\u00c3\u00bcrfel<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si tratta di un dado della linea &#8220;<em><a href=\"https:\/\/www.lien-ying.de\"><strong>Lien Ying<\/strong><\/a><\/em>&#8221; (in questo caso &#8220;Die Asiatische K\u00c3\u00bcche&#8221;) , abbastanza diffusa qui da noi.<br \/>\nNel momento in cui l&#8217;ho acquistato, devo essere sincera, non ho letto <del>tutte le porcherie<\/del> tutti gli ingredienti contenuti in esso.<\/p>\n<p style=\"text-align: justify;\">Ma va da se che, se lo vendono, qualcuno lo compra anche&#8230; e sicuramente non sono la sola.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15876\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167.jpg\" alt=\"\" width=\"2250\" height=\"4000\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167.jpg 2250w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190207_130402-e1549543604167-576x1024.jpg 576w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\">Il dado l&#8217;ho inserito direttamente nella pentola calda, cosi&#8217; da dargli l&#8217;opportunita&#8217; di sciogliersi direttamente con il calore e di non inserire ulteriore olio.<br \/>\nPochi istanti dopo ho\u00c2\u00a0 aggiunto i cubetti di pollo e li ho fatti cuocere ben bene.<\/p>\n<p style=\"text-align: justify;\">Tobias e Stephan sono arrivati perfettamente in tempo, cosi&#8217; da decidere di aggiungere anche la pasta &#8211; chiaramente cinese\u00c2\u00a0 e cotta in anticipo &#8211; nella pentola con la carne.<\/p>\n<p style=\"text-align: justify;\">Il &#8220;miscuglio&#8221; e&#8217; stato decisamente buono e la preparazione, pasta inclusa non ha dei tempi di attesa biblici.<br \/>\nPurtroppo, per voi, non ho fatto a tempo a fotografare, avendo sbranato il contenuto del piatto&#8230;<\/p>\n<p style=\"text-align: justify;\">A mio avviso si potrebbe anche fare alla mattina, cosi&#8217; da darne un po&#8217; a Tobias da portare a scuola quando non va in mensa (e non ha selezionato nulla dal menu) ma in quei giorni in cui deve restare sino alle 17.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ogni tanto Tobias resta a scuola a mangiare anche il giovedi quando, a ben vedere, non avrebbe nessuna lezione nel pomeriggio. Ma oggi ha deciso di arrivare a casa in orario.<\/p>\n","protected":false},"author":2,"featured_media":15875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,138],"tags":[126],"class_list":["post-15873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-piatti_unici","tag-salsa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15873"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15873\/revisions"}],"predecessor-version":[{"id":15888,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15873\/revisions\/15888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15875"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}