{"id":15826,"date":"2019-04-06T10:08:51","date_gmt":"2019-04-06T09:08:51","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15826"},"modified":"2019-03-23T16:19:48","modified_gmt":"2019-03-23T15:19:48","slug":"scrittoio","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/04\/06\/scrittoio\/","title":{"rendered":"Scrittoio"},"content":{"rendered":"<p style=\"text-align: justify;\">E con questo ultimo mobile siamo finalmente arrivati al termine della presentazione.<\/p>\n<p><!--more--><\/p>\n<p>Ma, soprattutto, alla loro disposizione, spero definitiva, in casa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15827\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333.jpg\" alt=\"\" width=\"2250\" height=\"4000\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333.jpg 2250w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/02\/IMG_20190129_193103-e1549286864333-576x1024.jpg 576w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Gli altri arrivi li potete visionare qui: <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/03\/10\/armadio\">armadio<\/a><\/strong><\/em>, <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/02\/12\/mobile-in-sala\/\">sala<\/a><\/strong><\/em>, <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/02\/06\/nuovi-mobili\/\">televisione<\/a><\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">Da subito Stephan ha detto che avrebbe avuto piacere nel piazzarlo nella nostra camera.<br \/>\nNon c&#8217;e&#8217; stato verso di fargli cambiare idea e, in una mattinata in cui\u00c2\u00a0 non ero presente, ha chiesto al vicino di aiutarlo nel trasporto al primo piano: non ho potuto evitarlo e mi sono ritrovata a fatto compiuto.<\/p>\n<p style=\"text-align: justify;\">E cosi&#8217;, ora, vedo la camera da letto un po&#8217; _troppo_ affollata.<br \/>\nVoi cosa ne pensate?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16318\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898.jpg\" alt=\"\" width=\"2250\" height=\"4000\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898.jpg 2250w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142355-e1553354216898-576x1024.jpg 576w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16319\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/03\/IMG_20190318_142404-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\">Si, dovrei trovare anche il momento giusto per riempirlo di libri&#8230; ma ora proprio non ce la faccio!<br \/>\nAnche perche&#8217; non saprei proprio come ri-organizzare la cosa.<br \/>\nSoprattutto tenendo conto che gli eventuali binder non ci stanno, se non nella parte alta, ma proprio non mi piaccioni posizionati li.<\/p>\n<p style=\"text-align: justify;\">PS: I libri sono dispersi per tutta la stanza.. \ud83d\ude42<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E con questo ultimo mobile siamo finalmente arrivati al termine della presentazione.<\/p>\n","protected":false},"author":2,"featured_media":16319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[94,156],"class_list":["post-15826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-diy","tag-lavori"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15826"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15826\/revisions"}],"predecessor-version":[{"id":16320,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15826\/revisions\/16320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/16319"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}