{"id":1571,"date":"2019-03-26T14:40:03","date_gmt":"2019-03-26T13:40:03","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/latte-non-omogeneizzato\/"},"modified":"2019-03-06T17:38:35","modified_gmt":"2019-03-06T16:38:35","slug":"latte-non-omogeneizzato","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/03\/26\/latte-non-omogeneizzato\/","title":{"rendered":"Latte non omogeneizzato"},"content":{"rendered":"<p style=\"text-align: justify;\">Una vicina mi ha fatto scoprire il latte fresco pastorizzato ma <strong>non omogeneizzato<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">E&#8217; stata una bella e strana scoperta.<br \/>\nIl gusto e&#8217; piu&#8217; morbido, corposo, riempie la bocca rispetto a quanto acquistato sino ad ora.<br \/>\n(ok, anche comparandolo al mio solito acquisto, con l&#8217;1,5% di grasso, e&#8217; comunque tutto un altro mondo)<\/p>\n<p style=\"text-align: justify;\">L&#8217;unico lato negativo e&#8217; che bisogna ricordarsi di agitare la confezione prima di utilizzarlo, tanto da poter mischiare la massa grassa al restante &#8220;siero&#8221;.<br \/>\nE di andare al negozio BIO per trovarlo.<\/p>\n<p style=\"text-align: justify;\">Ho fatto una ricerchina su Internet, ed ho scoperto che anche in Italia esiste questo tipo di latte e penso che in Italia questo tipo di latte NON-omogeneizzato si possa trovare con questo nome &#8220;latte fresco intero a lavorazione tradizionale inglese&#8221;.<br \/>\n(Correggetemi se sbaglio!! )<\/p>\n<p style=\"text-align: justify;\">Ebbene, non so come mai (effettivamente non l&#8217;ho ancora capito), ma costa anche qualche centesimo in _meno_ di altri latti che si trovano qui a Patatolandia.<\/p>\n<p style=\"text-align: justify;\">Quello che ho trovato (e provato) e&#8217; della Dennree, marca totalmente biologica, che mi e&#8217; costato 0,89cent il cartoccio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15341\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th2.jpg\" alt=\"\" width=\"235\" height=\"415\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th2.jpg 235w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th2-85x150.jpg 85w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th2-170x300.jpg 170w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/p>\n<p style=\"text-align: justify;\">Ma che cosa e&#8217; un latte &#8220;omogeneizzato&#8221;, quindi da cosa differisce rispetto al normale latte comune?<\/p>\n<p style=\"text-align: justify;\">Il latte viene trattato meccanicamente dopo la pastorizzazione al fine di emulsionare i lipidi in piccole goccioline di dimensioni approssimativamente simili tra loro, in modo da distribuirsi uniformemente nel latte stesso.<br \/>\nQueste particelle, assorbendo la maggior parte del contenuto proteico del latte, fanno s\u00c3\u00ac che l\u00e2\u20ac\u2122emulsione si stabilizzi e impediscono che la panna raggiunga l\u00e2\u20ac\u2122estremit\u00c3\u00a0 superiore.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15342\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-14.jpg\" alt=\"\" width=\"474\" height=\"314\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-14.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-14-150x99.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-14-300x199.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/p>\n<p style=\"text-align: justify;\">Confrontandolo ad altro latte Bio, siamo intorno ai 30cents in meno (in media!).<\/p>\n<p style=\"text-align: justify;\">In commercio, oltre ai diversi tipi di latte provenienti da animali diversi (capra, mucca, etc..), abbiamo anche tutta una <strong><a href=\"https:\/\/www.salepepe.it\/ingredienti\/tipi-di-bibite\/latte\/\"><em>diversa topologia<\/em><\/a><\/strong>:<\/p>\n<p style=\"text-align: justify;\"><strong>Crudo<\/strong>: non subisce alcun trattamento. \u00c3\u00a8 il pi\u00c3\u00b9 completo a livello nutrizionale.<\/p>\n<p style=\"text-align: justify;\"><strong>Lavorazione inglese<\/strong>: \u00c3\u00a8 latte fresco pastorizzato, ma non omogeneizzato.<\/p>\n<p style=\"text-align: justify;\"><strong>Latte intero<\/strong><br \/>\n<em>A lunga durata<\/em>: Metodi come la microfiltrazione o la pastorizzazione a temperature elevate Aumentano la durata rispetto al tipo fresco.<br \/>\n<em>Latte anticolesterolo<\/em>: pu\u00c3\u00b2 essere addizionato di Omega 3, che abbassano il livello di colesterolo, o di steroli vegetali, che ne riducono l\u00e2\u20ac\u2122assorbimento. Per legge \u00c3\u00a8 definito bevanda a base di latte.<br \/>\n<em>Arricchito<\/em>: \u00c3\u00a8 addizionato con nutrienti specifici: vitamine, fibre probiotiche, minerali o antiossidanti. Anch\u00e2\u20ac\u2122esso \u00c3\u00a8 una bevanda a base di latte.<\/p>\n<p style=\"text-align: justify;\"><strong>Come viene lavorato:<\/strong><br \/>\nIl latte fresco in commercio subisce 3 trattamenti principali:<br \/>\n<em>Raffreddamento:<\/em> a 4\u00c2\u00b0 subito dopo la mungitura;<br \/>\n<em>Pastorizzazione,<\/em> cio\u00c3\u00a8 riscaldamento a 72-75\u00c2\u00b0 per 15 secondi (muoiono i germi ma non tutti i fermenti \u00e2\u20ac\u0153buoni\u00e2\u20ac\u009d);<br \/>\n<em>Omogenizzazione<\/em>, cio\u00c3\u00a8 frantumazione dei globuli di grasso. Per il latte a lunga conservazione si aggiunge il Metodo UHT, cio\u00c3\u00a8 riscaldamento a 135-140\u00c2\u00b0 per 2 secondi: il latte ha meno flora batterica e per questo si conserva fuori dal frigorifero per 3 mesi.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vicina mi ha fatto scoprire il latte fresco pastorizzato ma non omogeneizzato.<\/p>\n","protected":false},"author":2,"featured_media":15342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,22],"tags":[],"class_list":["post-1571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1571"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1571\/revisions"}],"predecessor-version":[{"id":15355,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1571\/revisions\/15355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15342"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}