{"id":15638,"date":"2019-02-01T10:30:48","date_gmt":"2019-02-01T09:30:48","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15638"},"modified":"2026-05-13T19:08:20","modified_gmt":"2026-05-13T17:08:20","slug":"torta-mele-con-latticello","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/02\/01\/torta-mele-con-latticello\/","title":{"rendered":"Torta di mele con latticello\/buttermilch"},"content":{"rendered":"<p style=\"text-align: justify;\">Tobias, durante il periodo natalizio, mi chiede sempre di preparare i suoi muffins speciali e preferiti: quelli allo <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/02\/10\/spekulatius\/\">Spekulatius<\/a><\/strong><\/em>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Figurarsi che e&#8217; anche arrivato a chiedermi di preparare questi biscotti direttamente a casa, senza aspettare le feste natalizie, cosi&#8217; che possiamo cucinare i muffins anche durante i restanti mesi dell&#8217;anno \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, dopo aver terminato anche l&#8217;ultimo pacco di biscotti a nostra disposizione, mi e&#8217; restato\u00c2\u00a0 circa 250ml di latticello\/buttermilch.<\/p>\n<p style=\"text-align: justify;\">Di preparare il pane (<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/02\/18\/irlanda_soda-bread\/\">soda bread<\/a><\/strong><\/em>) proprio non ne avevo voglia.<\/p>\n<p>Ho pensato anche ad altri muffins ma, girando in rete, ho scovato <em><strong><a href=\"https:\/\/www.onecakeinamillion.com\/2013\/04\/torta-alle-mele-e-latticello.html\">questa<\/a><\/strong><\/em> ottima (e semplice) torta di mele.<\/p>\n<figure id=\"attachment_15670\" aria-describedby=\"caption-attachment-15670\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15670 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0186-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15670\" class=\"wp-caption-text\">Torta di mele con latticello\/buttermilch<\/figcaption><\/figure>\n<p>Ecco a voi, quindi, la &#8220;<strong>Torta alle mele e latticello<\/strong>&#8221;<\/p>\n<div style=\"text-align: justify;\">\n<p><strong>Ingredienti<\/strong><\/p>\n<\/div>\n<pre style=\"text-align: justify;\">2 uova\r\n120 gr zucchero\r\n250 gr latticello\/buttermilch\r\n350 gr farina 00\r\n1\/2 bustina lievito\r\n2 mele\r\n1 pizzico di sale\r\nmandorle a scaglie<\/pre>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Montate le uova con lo zucchero e accendete il forno a 180\u00c2\u00b0.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\n<p>Unite il latticello e tutti gli ingredienti secchi setacciati, tagliate le mele a dadini e unitele al composto, un pizzico di sale e mescolate con delicatezza.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">Versate il composto in uno stampo rettangolare foderato con carta da forno inumidita (<i>cos\u00c3\u00ac che si attacchi a tutti i lati<\/i>), spolverate con le mandorle a scaglie ed infornate per circa 30 minuti.<\/div>\n<div style=\"text-align: justify;\">\n<p>Fate raffreddare, sformate e tagliate a quadratoni.<\/p>\n<\/div>\n<div>\n<figure id=\"attachment_15671\" aria-describedby=\"caption-attachment-15671\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15671 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_0187-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15671\" class=\"wp-caption-text\">Torta di mele con latticello\/buttermilch<\/figcaption><\/figure>\n<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00c2\u00a0Come sempre mi succede, non mi organizzo prima con i diversi ingredienti per le mie preparazioni, fatte alcune eccezioni, ma cerco di attingere da quanto dispongo a casa.<\/div>\n<div style=\"text-align: justify;\">Alla preparazione originale ho aggiunto una spruzzata di cannella.. e, non avendo le mandorle a scaglie, ho cosparso leggermente di mandorle grattugiate.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\n<p>Ho poi usato una normale tortiera a cerniera da 22cm., con carta forno sul fondo.<\/p>\n<\/div>\n<div>\n<figure id=\"attachment_15695\" aria-describedby=\"caption-attachment-15695\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15695 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190124_172631-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15695\" class=\"wp-caption-text\">Torta di mele con latticello\/buttermilch<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<\/div>\n<div>\u00c2\u00a0Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tobias, durante il periodo natalizio, mi chiede sempre di preparare i suoi muffins speciali e preferiti: quelli allo Spekulatius.<\/p>\n","protected":false},"author":2,"featured_media":15695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[107,88,183],"class_list":["post-15638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-frutta","tag-frutta_secca","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15638"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15638\/revisions"}],"predecessor-version":[{"id":51985,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15638\/revisions\/51985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15695"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}