{"id":15578,"date":"2019-01-24T11:31:51","date_gmt":"2019-01-24T10:31:51","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15578"},"modified":"2020-04-21T06:59:18","modified_gmt":"2020-04-21T05:59:18","slug":"panini-al-latte-di-tina-scalisi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/01\/24\/panini-al-latte-di-tina-scalisi\/","title":{"rendered":"Panini al latte di Tina Scalisi"},"content":{"rendered":"<p style=\"text-align: justify;\">Questa volta ho provato a preparare questi panini al latte con Vera<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La ricetta l&#8217;ho trovata su FB, e devo quindi ringraziare &#8220;Tina Scalisi&#8221; per averla divulgata e messa a disposizione di tutti.<\/p>\n<p style=\"text-align: justify;\">L&#8217;autrice definisce questi panini al latte come &#8220;morbidoni&#8221;, come darle torto?<\/p>\n<p style=\"text-align: justify;\">Ma vediamo in dettaglio la loro preparazione&#8230;<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre style=\"text-align: justify;\">250 di latte o met\u00c3\u00a0 acqua e met\u00c3\u00a0 latte\r\n500 di farina 0 ( oppure 250 di manitoba e 250 di 0 )\r\n100 di lievito madre solida o 70 di li.co.li. \r\n1 un cucchiaino di miele \r\n1 cucchiaino e mezzo di sale \r\n50 di olio evo<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciogliete il lievito (licoli nel mio caso specifico) nel liquido, facendogli fare una bella schiuma (ho optato per utilizzare solo latte).<\/p>\n<p style=\"text-align: justify;\">Aggiungete a poco a poco la farina e anche l&#8217;olio, poi mettete il sale e impastate fino ad ottenere un panetto liscio e omogeneo.<\/p>\n<figure id=\"attachment_15580\" aria-describedby=\"caption-attachment-15580\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15580 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_140212-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15580\" class=\"wp-caption-text\">Panini al latte<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Mettete in una ciotola e fate lievitare fino al raddoppio.<\/p>\n<p>Una volta raggiunta la lievitazione, ricavate delle palline di 70\/80 gr. ciascuna.<\/p>\n<p style=\"text-align: justify;\">Posizionate i panini sulla teglia foderata di carta forno e rimettete a lievitare di nuovo coperti con pellicola.<\/p>\n<figure id=\"attachment_15581\" aria-describedby=\"caption-attachment-15581\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15581 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_172722-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15581\" class=\"wp-caption-text\">Panini al latte<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quando saranno ben lievitati infornate in forno caldo a 180\u00c2\u00b0.<\/p>\n<p>Prima di infornare spennellate con latte e,\u00c2\u00a0 a piacere, cospargete con semini di sesamo o papavero.<br \/>\nCuocete per circa 20 minuti, comunque fino a doratura.<\/p>\n<figure id=\"attachment_15582\" aria-describedby=\"caption-attachment-15582\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15582 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_141625-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15582\" class=\"wp-caption-text\">Panini al latte<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Almeno a casa mia, non hanno fatto a tempo a raffreddare che sono stati subito &#8220;testati&#8221; dal ragazzo.<\/p>\n<figure id=\"attachment_15583\" aria-describedby=\"caption-attachment-15583\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15583 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175749-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15583\" class=\"wp-caption-text\">Panini al latte<\/figcaption><\/figure>\n<p>Buoni, facili e &#8220;morbidosi&#8221;.<\/p>\n<figure id=\"attachment_15584\" aria-describedby=\"caption-attachment-15584\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15584 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190117_175740-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15584\" class=\"wp-caption-text\">Panini al latte<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa volta ho provato a preparare questi panini al latte con Vera<\/p>\n","protected":false},"author":2,"featured_media":15583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[112],"class_list":["post-15578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15578"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15578\/revisions"}],"predecessor-version":[{"id":21950,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15578\/revisions\/21950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15583"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}