{"id":15518,"date":"2019-01-12T11:50:23","date_gmt":"2019-01-12T10:50:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15518"},"modified":"2024-09-22T18:54:12","modified_gmt":"2024-09-22T16:54:12","slug":"sommer-sauer-brot-pane-estivo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/01\/12\/sommer-sauer-brot-pane-estivo\/","title":{"rendered":"Sommer-Sauer Brot (Pane Estivo)"},"content":{"rendered":"<p style=\"text-align: justify;\">Buon giorno!<\/p>\n<p style=\"text-align: justify;\">Visto il clima nevoso di qui a Patatolandia, ho pensato di risollevarmi il morale preparando questo &#8220;<strong>Sommer-Sauer Brot<\/strong>&#8221; pane.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La ricetta seguita l&#8217;ho presa dalla rivista &#8220;<strong>BROT<\/strong>&#8221; (rigorosamente in lingua tedesca), numero 5\/18.<\/p>\n<p style=\"text-align: justify;\">Non ho tanti numeri di questa rivista di panificazione, ma ne ero rimasta incuriosita cosi&#8217; tanto da acquistare almeno 2 numeri.<\/p>\n<figure id=\"attachment_15521\" aria-describedby=\"caption-attachment-15521\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15521 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130035-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130035-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130035-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130035-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130035-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15521\" class=\"wp-caption-text\">Sommer-Sauer Brot (Pane Estivo)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Per la preparazione di questo pane ho usato la farina del Mulino di Monaco.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Sommer-Sauer Brot (Pane Estivo)<br \/>\n<\/strong><\/p>\n<pre><strong>Sauerteig (Pre-impasto)\r\n<\/strong>300gr Semola (Hartweizengriess)\r\n200gr di acqua tiepida\r\n15gr di licoli (Vera rinfrescata)\r\n\r\n<strong>Hauptteig (Impasto)<\/strong>\r\n<strong>Sauerteig<\/strong>\r\n300gr di 550 (ossia la farina 0)\r\n200gr di acqua tiepida\r\n14gr di sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<figure id=\"attachment_15522\" aria-describedby=\"caption-attachment-15522\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15522 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130242-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130242-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130242-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130242-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_130242-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15522\" class=\"wp-caption-text\">Sommer-Sauer Brot (Pane Estivo)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Unite tutti gli ingredienti per preparare\u00c2\u00a0 il &#8220;<strong>Sauerteig&#8221;<\/strong> e lasciate riposare a temperatura ambiente (tra i 20-22gradi) tra le 12-16 ore.<br \/>\nNel mio caso, ho messo tutto in cella di lievitazione, dato che fa un po&#8217; piu&#8217; che freschino in casa rispetto ai 20gradi suggeriti.<\/p>\n<p style=\"text-align: justify;\">Trascorso il tempo, unite tutti gli ingredienti e impastate\u00c2\u00a0 a mano.<br \/>\n<em>IO: ho usato il Kenwood.<\/em><br \/>\n<em>Ho sciolto il Sauerteig con l&#8217;acqua, ho poi unito la farina ed ho azionato ad 1-1,5 di velocita&#8217;.<\/em><br \/>\n<em>Sono bastati pochi minuti di rotazione, poi ho inserito il sale sciogliendolo in un goccio di acqua, detraendolo dal secondo impasto.<\/em><\/p>\n<p style=\"text-align: justify;\">Una volta che si e&#8217; incordato l&#8217;impasto, lasciatelo a temperatura ambiente (<em>l&#8217;ho messo in una ciotola coperta, ed ancora nella cella<\/em>) per 40 minuti.<\/p>\n<p style=\"text-align: justify;\">Pirlate l&#8217;impasto e mettetelo in un cestino da lievitazione (la chiusura va sotto) per un&#8217;oretta.<\/p>\n<p style=\"text-align: justify;\">Pre-riscaldate il forno a 250gradi, inserirendo una pentola di ghisa \/ dutch oven (cosi&#8217; da riscaldarla), con relativo coperchio.<br \/>\nQuando sara&#8217; il momento di cuocere il pane (ho fatto la &#8220;prova dito&#8221; ed ha impiegato meno di un&#8217;ora), scaraventate l&#8217;impasto nella pentola e chiudetela con\u00c2\u00a0 il suo coperchio.<\/p>\n<figure id=\"attachment_15526\" aria-describedby=\"caption-attachment-15526\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15526 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131405-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131405-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131405-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131405-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131405-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15526\" class=\"wp-caption-text\">Sommer-Sauer Brot (Pane Estivo)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dopo 10minuti, abbassate la temperatura a 230 e continuate per 35minuti.<br \/>\nGli ultimi 10 minuti di cottura sono stati effettuati rimuovendo il coperchio della pentola, cosi&#8217; da dorare un po&#8217; il pane.<\/p>\n<p style=\"text-align: justify;\">Una volta sfornato non lo abbiamo lasciato riposare abbastanza e raffreddare, ma lo abbiamo tagliato subito.<\/p>\n<p style=\"text-align: justify;\">Il sapore e&#8217; buono ma, personalmente, non mi piacciono molto i buchi estremi che si sono creati (si possono vedere prossima foto postata).<br \/>\nNon sono se sono corretti o a causa di qualche errore, dato che di mia iniziativa ho effettuato delle pieghe a 3&#8230;<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, la prossima volta che lo faro&#8217;, e succedera&#8217; sicuramente, vorrei provarlo a cuocere nella pentola <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/07\/15\/tupperware\/\">Tupperware<\/a><\/strong><\/em><\/p>\n<figure id=\"attachment_15527\" aria-describedby=\"caption-attachment-15527\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15527 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131745-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131745-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131745-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131745-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190111_131745-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15527\" class=\"wp-caption-text\">Sommer-Sauer Brot (Pane Estivo)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>AGGIORNAMENTO del 14 gennaio 2019.<\/strong><\/p>\n<p style=\"text-align: justify;\">Non ho aspettato molto a rifare lo stesso pane.<br \/>\nGli ingredienti e la preparazione sono stati li stessi.<br \/>\nQuesta volta ho inserito tutto direttamente nella mia pentola Tupperware Ultra Pro.<br \/>\nDopo 40minuti a TA (circa 23gradi), ho messo a lievitare a 28gradi (per un&#8217;oretta).<\/p>\n<p style=\"text-align: justify;\">Al momento della cottura, ho pre-riscaldato il forno a 250gradi, inserendo direttamente la pentola con il suo contenuto (impasto) ed il coperchio.<br \/>\nHo poi\u00c2\u00a0 lasciato 15minuti prima di abbassare il calore a 230.<br \/>\nForma perfetta \ud83d\ude42<\/p>\n<figure id=\"attachment_15565\" aria-describedby=\"caption-attachment-15565\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15565\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/IMG_20190114_123204-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15565\" class=\"wp-caption-text\">Sommer-Sauer Brot (Pane Estivo) &#8211; Cotto nel Tupperware<\/figcaption><\/figure>\n<p><strong>AGGIORNAMENTO del 13 ottobre 2023.<\/strong><\/p>\n<p style=\"text-align: justify;\">Cercavo un pane semplice per smaltire un po&#8217; di farina e, allo stesso tempo, per utilizzare il mio licoli.<br \/>\nE mi e&#8217; venuto in mente.<\/p>\n<p style=\"text-align: justify;\">Farine utilizzate:<\/p>\n<ul>\n<li style=\"text-align: justify;\">semola &#8211; Edeka mein Bayer &#8211; 22% di proteine<\/li>\n<li style=\"text-align: justify;\">Weizenmehl &#8211; Bio Hit 550 &#8211; 11% di proteine<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&#8217;impasto per la<em> prima lievitazione<\/em> e&#8217; stato lasciato a temperatura ambiente (intorno ai 22 gradi), dalle 17 alle 9:30 del mattino successivo.<br \/>\nPer la <em>seconda lievitazione<\/em> ho effettuato delle pieghe a tre, pirlato e reinserito l&#8217;impasto nella ciotola, lasciandola a temperatura ambiente.<br \/>\nProbabilmente non ho impastato a lungo e correttamente, in quanto la massa e&#8217; rimasta un po&#8217; appiccicosa.<br \/>\nCome per la seconda prova ho deciso di cuocere nella <em>Tupperware<\/em>, al termine dei 40 minuti ho effettuato un giro di pieghe a 3, poi ho inserito nella pentola per lievitare.<\/p>\n<p><strong>AGGIORNAMENTO del 21 settembre 2024.<\/strong><\/p>\n<p>Stesso procedimento, farine probabilmente diverse.<br \/>\nStessa cottura in Tupperware.<\/p>\n<figure id=\"attachment_46277\" aria-describedby=\"caption-attachment-46277\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46277\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_191751-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_191751-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_191751-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_191751-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_191751-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46277\" class=\"wp-caption-text\">SommerBrot<\/figcaption><\/figure>\n<figure id=\"attachment_46278\" aria-describedby=\"caption-attachment-46278\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46278\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_192934-783x1024.jpg\" alt=\"\" width=\"525\" height=\"687\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_192934-783x1024.jpg 783w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_192934-115x150.jpg 115w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_192934-229x300.jpg 229w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/01\/ok_IMG_20240921_192934-768x1005.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46278\" class=\"wp-caption-text\">SommerBrot<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buon giorno! Visto il clima nevoso di qui a Patatolandia, ho pensato di risollevarmi il morale preparando questo &#8220;Sommer-Sauer Brot&#8221; pane.<\/p>\n","protected":false},"author":2,"featured_media":15523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[249,112,111],"class_list":["post-15518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-dutch_oven","tag-licoli","tag-tupperware"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15518"}],"version-history":[{"count":16,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15518\/revisions"}],"predecessor-version":[{"id":46279,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15518\/revisions\/46279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15523"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}