{"id":1526,"date":"2013-01-26T18:40:01","date_gmt":"2013-01-26T17:40:01","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/sempre-lavorare\/"},"modified":"2018-09-01T20:24:52","modified_gmt":"2018-09-01T19:24:52","slug":"sempre-lavorare","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/01\/26\/sempre-lavorare\/","title":{"rendered":"..sempre lavorare.."},"content":{"rendered":"<p style=\"text-align: justify;\">Magari con l&#8217;arrivo della stagione fredda, molte persone potrebbero pensare che i lavori in casa nostra si fermino.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">E qui casca l&#8217;asino!<\/p>\n<p style=\"text-align: justify;\">NON CI FERMIAMO&#8230;<\/p>\n<p style=\"text-align: justify;\">Chisa&#8217; come mai, ho sempre un sacco di idee da far fare al &#8220;pover&#8217;uomo&#8221; che non so ancora come mi faccia a sopportare.<\/p>\n<p style=\"text-align: justify;\">A dire il vero, le mie sono semplici cose, e&#8217; lui che le vuole fare da perfettino quale e&#8217; (ma solo in alcune situazioni, non nella sua normalita&#8217; quotidiana) e le ingigantisce totalmente.<\/p>\n<p style=\"text-align: justify;\">Qui siamo in cantina, alle prese con la posa di ulteriori piastrelle.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12436\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5688.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5688.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5688-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5688-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><br \/>\nAvevo una vecchia cucina, nessuno qui l&#8217;ha voluta acquistare, cosi&#8217; l&#8217;abbiamo riposizionata e la useremo come stoccaggio cibo (ed altro).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12437\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5968.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5968.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5968-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5968-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Ed eccola finita, con tanto di luci \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12438\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5969.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5969.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5969-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5969-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12435\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5686.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5686.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5686-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5686-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Inutile far notare che il top e&#8217; stato totalmente cambiato&#8230;<br \/>\nAvendo rimosso il lavandino ed il piano cottura.<\/p>\n<p style=\"text-align: justify;\">Approposito, nessuno ha bisogno di un lavandino ad angolo di fragranite della Franke?<\/p>\n<p style=\"text-align: justify;\">Di un piano cottura e di una cappa?<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magari con l&#8217;arrivo della stagione fredda, molte persone potrebbero pensare che i lavori in casa nostra si fermino.<\/p>\n","protected":false},"author":2,"featured_media":12435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[156],"class_list":["post-1526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-lavori"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1526"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1526\/revisions"}],"predecessor-version":[{"id":12439,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1526\/revisions\/12439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12435"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}