{"id":15066,"date":"2018-12-22T09:53:17","date_gmt":"2018-12-22T08:53:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15066"},"modified":"2022-12-15T14:27:02","modified_gmt":"2022-12-15T13:27:02","slug":"biscotti-avvento-2018-2","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/12\/22\/biscotti-avvento-2018-2\/","title":{"rendered":"Biscotti Avvento 2018 &#8211; Parte seconda"},"content":{"rendered":"<p style=\"text-align: justify;\">Non siamo mai contenti&#8230;<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho dovuto incrementare la preparazione delle mie quantita&#8217; di biscotti per l&#8217;Avvento.<\/p>\n<p>Questa volta, pero&#8217;, ho avuto in cucina un ospite speciale, tanto che alla fine me ne sono andata io, lasciandolo solo al suo lavoro:<\/p>\n<p style=\"text-align: center;\">Geppetto (ma questa e&#8217; un&#8217;altra storia&#8230;).<\/p>\n<p style=\"text-align: justify;\">La seconda infornata e&#8217; stata molto produttiva, soprattutto con ricette di biscotti che non avev mai fatto prima.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Giusto per terminare alcuni ingredienti aperti, e di cui Geppo ha contribuito al loro utilizzo, ho preparato<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15764\" aria-describedby=\"caption-attachment-15764\" style=\"width: 4000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15764\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425.jpg\" alt=\"\" width=\"4000\" height=\"2250\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425.jpg 4000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170425-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15764\" class=\"wp-caption-text\">Talleri ripieni di crema alla nocciola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; <a href=\"https:\/\/www.oetker.de\/rezepte\/r\/gefuellte-nuss-nougat-taler.html\"><em>Talleri ripieni di crema alla nocciola<\/em><\/a> ( ricetta DtOetker )<br \/>\n<\/strong><\/p>\n<pre>200 g di farina\r\n75 g. Maizena\r\n50 g. Farina di mandorle ( macinate )\r\n100 g di zucchero\r\n1 uovo (taglia M)\r\n175 g di burro morbido\r\n\r\n<strong>Ripieno<\/strong>:\r\n100 g. Dr. Oetker Nuss-Nougat\r\n\r\n<strong>Per decorare:<\/strong>\r\n150 g. Cioccolato al latte per copertura<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Create l&#8217;impasto:<br \/>\n<\/strong>Mescolate la farina con la maizena in una terrina.<br \/>\nAggiungete gli ingredienti rimanenti per l&#8217;impasto e lavorate il tutto con un frullatore (uncino per impasto) prima alla velocita&#8217;\u00c2\u00a0 pi\u00c3\u00b9 bassa, poi aumentando lentamente sino ad ottenere un impasto omogeneo.<\/p>\n<p style=\"text-align: justify;\">Lasciate riposare la pasta per circa 30 minuti nel frigo, dopo averne fatto un panetto ed averla avvoltolata nella pellicola.<br \/>\nCoprite la teglia con la carta da forno.<\/p>\n<p style=\"text-align: justify;\"><strong>Preriscaldate il forno:<\/strong><br \/>\nCalore superiore \/ inferiore: circa 200 \u00c2\u00b0 C<br \/>\nAria calda: circa 180 \u00c2\u00b0 C<\/p>\n<p style=\"text-align: justify;\">Impastate\u00c2\u00a0 su di piano di lavoro leggermente infarinato, spianate l&#8217;impasto ad una altezza di 0,5cm e create dei &#8220;talleri&#8221; di circa 4cm di diametro.<\/p>\n<p style=\"text-align: justify;\">Posizionateli sulla placca ricoperta di carta forno.<\/p>\n<p style=\"text-align: justify;\">Mettete la teglia in forno pre-riscaldato, posizionandola nel mezzo.<br \/>\nCuocete per circa 12 minuti.<\/p>\n<p style=\"text-align: justify;\">Fate riposare i biscotti prima di staccarli dalla carta, e lasciateli raffreddare su una griglia.<\/p>\n<p style=\"text-align: justify;\"><strong>Ripieno<br \/>\n<\/strong>Scaldate a bagnomaria la crema di nocciole.<\/p>\n<figure id=\"attachment_15139\" aria-describedby=\"caption-attachment-15139\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15139 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_161725-e1545235969606-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_161725-e1545235969606-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_161725-e1545235969606-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_161725-e1545235969606-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_161725-e1545235969606-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15139\" class=\"wp-caption-text\">Talleri ripieni di crema alla nocciola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Spalmate la crema su meta&#8217; dei biscotti e richiudeteli con gli altri.<br \/>\nA questo punto potreste anche usare il cioccolato di copertura ma, onestamente, erano buoni anche e solo cosi&#8217;&#8230;<\/p>\n<figure id=\"attachment_15127\" aria-describedby=\"caption-attachment-15127\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15127\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat.jpg\" alt=\"\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat.jpg 1000w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/nougat-100x100.jpg 100w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-15127\" class=\"wp-caption-text\">DrOetker &#8211; Nuss-Nougat<\/figcaption><\/figure>\n<figure id=\"attachment_15129\" aria-describedby=\"caption-attachment-15129\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15129 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_170530-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_170530-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_170530-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_170530-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_170530-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15129\" class=\"wp-caption-text\">Talleri ripieni di crema alla nocciola &#8211; cotti<\/figcaption><\/figure>\n<figure id=\"attachment_15138\" aria-describedby=\"caption-attachment-15138\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15138 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170411-e1545235923636-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170411-e1545235923636-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170411-e1545235923636-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170411-e1545235923636-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170411-e1545235923636-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15138\" class=\"wp-caption-text\">Talleri ripieni di crema alla nocciola<\/figcaption><\/figure>\n<figure id=\"attachment_15141\" aria-describedby=\"caption-attachment-15141\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15141 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170420-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170420-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170420-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170420-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_170420-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15141\" class=\"wp-caption-text\">Talleri ripieni di crema alla nocciola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Devo ammettere che la consistenza di questo impasto era ottimo, nonostante la mia incapacita&#8217;, sono riuscita perfettamente a prepararlo.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>A questo punto ha fatto seguito una<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15132\" aria-describedby=\"caption-attachment-15132\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15132 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_181347-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_181347-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_181347-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_181347-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_181347-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15132\" class=\"wp-caption-text\">Frolla al Cocco, ricetta di Montersino<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; <\/strong><strong>Frolla al Cocco, ricetta di Montersino<\/strong><\/p>\n<pre>250 gr di burro\r\n250 gr di zucchero a velo\r\n500 gr di farina 180w\r\n135 gr tuorlo d'uovo\r\n100 gr di cocco rap\u00c3\u00a8<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p>Lavorate in planetaria con la foglia il burro e lo zucchero.<br \/>\nUnite i tuorli e infine le farine.<\/p>\n<p>Fate riposare la frolla in frigorifero per un paio di ore.<\/p>\n<p>Stendete e riempite gli stampi per tartellette o formare biscotti.<br \/>\nCuocete in forno a 180\u00c2\u00b0.<\/p>\n<figure id=\"attachment_15131\" aria-describedby=\"caption-attachment-15131\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15131 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_173154-e1545241348166-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_173154-e1545241348166-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_173154-e1545241348166-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_173154-e1545241348166-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_173154-e1545241348166-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15131\" class=\"wp-caption-text\">Frolla al Cocco, ricetta di Montersino<\/figcaption><\/figure>\n<p>Non ho terminato la frolla al cocco, me ne e&#8217; restato ancora un panetto pronto che ho messo nel congelatore.<br \/>\nDovro&#8217; usarlo al piu&#8217; presto&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15130 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_174729-e1545236431799-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_174729-e1545236431799-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_174729-e1545236431799-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_174729-e1545236431799-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181215_174729-e1545236431799-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">E per terminare la carrellata di quest&#8217;anno, ecco una frolla dei Fables, con la quale volevo preparare degli &#8220;<strong><em><a href=\"https:\/\/blog.giallozafferano.it\/fablesucre\/occhi-di-bue-biscotti\/\">occhi di bue<\/a><\/em><\/strong>&#8220;<\/p>\n<p><strong>Ingredienti &#8211; Occhi di Bue<br \/>\n<\/strong><\/p>\n<pre>250 gr di farina 00\r\n150 gr di burro\r\n100 gr di zucchero a velo\r\n40 gr di uovo intero\r\n6 gr di lievito per dolci\r\nbuccia di limone grattugiata\r\nun pizzico di sale<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavorate lo zucchero a velo con il burro senza montare, sbattete l&#8217;uovo con un pizzico di sale e aggiungetelo poco alla volta, unite poi la buccia di limone grattugiata e la farina setacciata con il lievito.<\/p>\n<p style=\"text-align: justify;\">Lavorate pochissimo, formate un panetto, avvolgetelo nella pellicola e riponetelo in frigorifero per circa 3 &#8211; 4 ore o addirittura un giorno.<\/p>\n<p style=\"text-align: justify;\">Riprendete il panetto, lavorate un poco senza scaldare l&#8217;impasto, stendete col mattarello e con un coppa pasta o con delle formine formare i biscotti creando le coppie, uno intero e l&#8217;altro col foro.<\/p>\n<p style=\"text-align: justify;\">Cuocete i biscotti in forno caldo a 180\u00c2\u00b0 per circa 10 &#8211; 12 minuti.<\/p>\n<p style=\"text-align: justify;\">Fat raffreddare i biscotti e poi farciteli con nutella, marmellata o crema e accoppiateli.<\/p>\n<p style=\"text-align: justify;\">&#8230; ma sul finire ho deciso di cambiare&#8230;<\/p>\n<p style=\"text-align: justify;\">Invece di usare uno stampino, per poi riempire (dato che avevo gia&#8217; fatto i &#8220;talleri&#8221;, comunque) avevo visto su internet un bellissimo centro tavola.<\/p>\n<p>E ci ho tentato..<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15133\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151814-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151814-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151814-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151814-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151814-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Questo e&#8217; l&#8217;impasto tagliato&#8230;<\/p>\n<p style=\"text-align: justify;\">E naturalmente una parte e&#8217; rimasta fuori..<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15134\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151826-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151826-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151826-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151826-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151826-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15135\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151817-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151817-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151817-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151817-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_151817-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Ho iniziato a cuocere i biscotti ma, circa 2 minuti prima del termine della loro cottura, ho inserito nel &#8220;cuore&#8221; 7 piccoli orsetti gommosi.<\/p>\n<p>La mia intenzione era di preparare i &#8220;biscotti di vetro&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15136\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_155129-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_155129-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_155129-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_155129-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_155129-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Onestamente non sono usciti malaccio.<\/p>\n<p style=\"text-align: justify;\">Bisogna solo fare attenzione che, dopo qualche minuto, gli orsetti si sciolgono e se si prolunga la cottura, allora iniziano a creare bruttissime bolle.<\/p>\n<p style=\"text-align: justify;\">Un altro problema che ho riscontrato, e&#8217; stato durante la fase di raffreddamento: la carta forno si e&#8217; incollata praticamente alla gommosita&#8217; creatasi, cosi&#8217; che, anche rimuovendo dolcemente i biscotti, non sono usciti totalmente perfetti.<\/p>\n<p style=\"text-align: justify;\">L&#8217;intenzione sara&#8217; quella di unire i quadrati, legandoli tra di loro con un nastrino ed utilizzando i piccoli fori fatti prima di cuocere.<br \/>\nAl loro interno mettero&#8217; una piccola candela.<\/p>\n<p>Staremo a vedere come e cosa risultera&#8217;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15153 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_201641-e1545311364881-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_201641-e1545311364881-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_201641-e1545311364881-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_201641-e1545311364881-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181216_201641-e1545311364881-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non siamo mai contenti&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22],"tags":[99,114,88],"class_list":["post-15066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food","tag-avvento","tag-droetker","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15066"}],"version-history":[{"count":14,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15066\/revisions"}],"predecessor-version":[{"id":40055,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15066\/revisions\/40055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15141"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}