{"id":15007,"date":"2018-12-08T09:35:26","date_gmt":"2018-12-08T08:35:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=15007"},"modified":"2023-07-30T17:38:09","modified_gmt":"2023-07-30T15:38:09","slug":"le-mie-tagliatelle","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/12\/08\/le-mie-tagliatelle\/","title":{"rendered":"Le mie tagliatelle"},"content":{"rendered":"<p style=\"text-align: justify;\">Era da tempo che non ci provavo, e l&#8217;ho fatto.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Ho tentato di fare delle tagliatelle completamente a mano ma&#8230; dire che sono uscite un mappazzone dopo la cottura e&#8217; decisamente fargli un complimento.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Ho usato la farina Patatolese definita per &#8220;Pasta e Spaetzle&#8221;, scoprendo in seguito che era un mix di semola e di farina di tipo &#8220;0&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15008\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101424-e1544114273966-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101424-e1544114273966-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101424-e1544114273966-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101424-e1544114273966-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101424-e1544114273966-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Da brava massaia ho usato 100gr di farina per ogni uovo inserito.<br \/>\nEssendo in 3, ho usato quindi 300gr e 3 uova in totale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15009 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101737-e1544114307746-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101737-e1544114307746-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101737-e1544114307746-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101737-e1544114307746-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_101737-e1544114307746-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Gia&#8217; l&#8217;impasto mi avrebbe dovuto insospettire&#8230;<br \/>\nE&#8217; risultato totalmente asciutto e decisamente ingestibile.<\/p>\n<p style=\"text-align: justify;\">Nonostante questo, ho tentato di proseguire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15010\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_103056-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_103056-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_103056-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_103056-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_103056-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo un lungo lavoro con il mattarello, ribaltando l&#8217;impasto da tutte le parti, sono riusciuta in qualche modo a stendere l&#8217;impasto in maniera fine.<br \/>\nAlmeno l&#8217;ho reputata tale, nonostante tutti i miei sforzi!<\/p>\n<p style=\"text-align: justify;\">Il taglio non e&#8217; stato perfetto ma.. mi sono accontentata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15013\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_121233-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_121233-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_121233-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_121233-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_121233-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Qui si vedono le tagliatelle che riposano beatamente.<br \/>\nIo?<br \/>\nUn po&#8217; meno!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15012\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_120031-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_120031-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_120031-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_120031-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181121_120031-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">A questo punto vi evito la fase di cottura ed impiattamento.<br \/>\nSappiate solamente che era immangiabile.<br \/>\nHo lasciato la pasta cuocere per pochi minuti, altrimenti avrei rischiato anche di creare un ammasso colloso (piu&#8217; di quanto sia risultato).<\/p>\n<p style=\"text-align: justify;\">Non demordo.<\/p>\n<p style=\"text-align: justify;\">Prima o poi ce la faro&#8217;.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era da tempo che non ci provavo, e l&#8217;ho fatto.<\/p>\n","protected":false},"author":2,"featured_media":15011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[153],"class_list":["post-15007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti","tag-homemade"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=15007"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15007\/revisions"}],"predecessor-version":[{"id":15014,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/15007\/revisions\/15014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15011"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=15007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=15007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=15007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}