{"id":1492,"date":"2013-03-08T18:40:00","date_gmt":"2013-03-08T17:40:00","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/auguri-a-tutte-le-donne-2\/"},"modified":"2023-03-08T10:56:32","modified_gmt":"2023-03-08T09:56:32","slug":"festa-donne-2013","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/03\/08\/festa-donne-2013\/","title":{"rendered":"Auguri a tutte le donne!"},"content":{"rendered":"<p style=\"text-align: justify;\">Per la Giornata Internazionale delle Donne di oggi, avevo pensato di preparare la torta mimosa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non so, non l&#8217;ho mai fatta, e mi incuriosiva.<\/p>\n<p style=\"text-align: justify;\">Purtroppo le avverse circostanza (bronchite di Tobias) ha fatto si che la nostra settimana si sia completamente rivoluzionata.<br \/>\nAlzatacce di notte dato che non riesce a dormire, strasbordi nel nostro letto alle 2 del mattino, movimenti notturni sino all&#8217;alba..<\/p>\n<p style=\"text-align: justify;\">E poi il lavoro, etc..etc..<\/p>\n<p style=\"text-align: justify;\">Fatto sta che e&#8217; da giorni che dovrei fare la spesa e non ce l&#8217;ho ancora fatta.<\/p>\n<p style=\"text-align: justify;\">Ora mai sono a secco di tutto l&#8217;indispensabile: camomilla per gli occhi, te e tisane varie, miele per la tosse, verdure per la dieta, e vai avanti cosi&#8217; che non finisce mai.<\/p>\n<p style=\"text-align: justify;\">Quindi, accontantatevi di un mazzetto striminzito scopiazzato e trovato da Google.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7042\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/MI09-Cuore-di-mimosa-con-rose-rosse-al-centro.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/MI09-Cuore-di-mimosa-con-rose-rosse-al-centro.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/MI09-Cuore-di-mimosa-con-rose-rosse-al-centro-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/MI09-Cuore-di-mimosa-con-rose-rosse-al-centro-100x100.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dimenticavo:<\/p>\n<p style=\"text-align: justify;\"><strong>Auguri ancora, DONNE!<\/strong><\/p>\n<p style=\"text-align: justify;\">PS: E se la premessa e&#8217; questa, non oso immaginare cosa mi potro&#8217; trovar alla Festa della Mamma!<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per la Giornata Internazionale delle Donne di oggi, avevo pensato di preparare la torta mimosa.<\/p>\n","protected":false},"author":2,"featured_media":7042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[123],"class_list":["post-1492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-festa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1492"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1492\/revisions"}],"predecessor-version":[{"id":41178,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1492\/revisions\/41178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7042"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}