{"id":14884,"date":"2019-01-29T14:40:41","date_gmt":"2019-01-29T13:40:41","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=14884"},"modified":"2020-07-14T16:33:01","modified_gmt":"2020-07-14T15:33:01","slug":"lasagne-alla-ricotta","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/01\/29\/lasagne-alla-ricotta\/","title":{"rendered":"Lasagne alla ricotta"},"content":{"rendered":"<p style=\"text-align: justify;\">Era prestissimo per il giorno di Natale ma, soprattutto, per pensare al pranzo della Vigilia\/Natale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per il mio carattere, invece, e&#8217; stato semplicemente TARDI.<\/p>\n<p style=\"text-align: justify;\">Non che non mi piacciano le improvvisate, ma <strong>solo<\/strong> quando queste sono spontanee e senza premeditazione.<\/p>\n<p style=\"text-align: justify;\">Non amo organizzarmi all&#8217;ultimo momento, soprattutto quando so che ho abbastanza tempo per pensare in anticipo.<\/p>\n<p style=\"text-align: justify;\">Ed anche questa volta non mi sono smentita.<\/p>\n<p style=\"text-align: justify;\">Oltre alla preparazione (anticipata) delle <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/01\/27\/lasagne-alla-bolognese\/\">lasagne alla Bolognese<\/a><\/strong><\/em>, ho cucinato anche una teglia di lasagne alla ricotta.<br \/>\nNon sia mai&#8230;<\/p>\n<p style=\"text-align: justify;\">Ed ancora GialloZafferano mi ha aiutato, con ottimi risultati e con spiegazioni dettagliatissime (che potete vedere direttamente seguendo il<em><strong><a href=\"https:\/\/ricette.giallozafferano.it\/Lasagnette-alla-ricotta.html\"> link originale<\/a><\/strong><\/em>).<\/p>\n<p style=\"text-align: justify;\">Per facilitarmi nella prossima preparazione della stessa ricetta, la ripropongo qui, come copia-incolla.<\/p>\n<p><strong>Ingredienti per una teglia 20&#215;30 cm<\/strong><\/p>\n<pre>Lasagne all'uovo 250 g\r\n Pepe bianco q.b.\r\n Timo q.b.\r\n Noce moscata q.b.\r\n Parmigiano reggiano 50 g\r\n Olio extravergine d'oliva 30\r\n\r\n<strong>per la crema di ricotta<\/strong>\r\n Ricotta vaccina 750 g\r\n Olio extravergine d'oliva 35 g\r\n Acqua calda 75 g\r\n Sale fino q.b.\r\n Pepe nero q.b.\r\n\r\n<strong>per la besciamella<\/strong>\r\nLatte fresco intero 750 g\r\n Farina 00 60 g\r\n Burro 75 g\r\n Noce moscata q.b.\r\n Parmigiano reggiano grattugiato 150 g\r\n Sale fino q.b.\r\n Pecorino grattugiato 50<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Per preparare le lasagne alla ricotta iniziate dalla <strong>preparazione della besciamella.<\/strong><\/p>\n<p style=\"text-align: justify;\">Prendete un tegame da bordi alti, fate sciogliere il burro a fiamma media e versatevi la farina.<br \/>\nMescolate con le fruste a mano fino a quando non otterrete un roux dal colore dorato. Quindi versate il latte leggeremente riscaldato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14953\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_152318-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_152318-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_152318-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_152318-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_152318-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiustate di sale e pepe e grattugiate della noce moscata.<br \/>\nContinuate la cottura a fuoco basso per altri 5-6 minuti per far addensare, mescolando con le fruste a mano per evitare che il composto si attacchi al fondo della pentola.<\/p>\n<p style=\"text-align: justify;\">Versate ora il Parmigiano ed il Pecorino grattugiati.<br \/>\nMescolate con una frusta per creare un composto omogeneo e privo di grumi. Trasferite la besciamella con formaggi in una ciotola capiente e copritela con pellicola alimentare trasparente a contatto per evitare la formazione della crosticina in superficie.<br \/>\nTenete da parte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14955 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_171805-e1546869242555-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_171805-e1546869242555-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_171805-e1546869242555-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_171805-e1546869242555-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_171805-e1546869242555-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Procedete con la <strong>preparazione della crema alla ricotta.<\/strong><br \/>\nVersate la ricotta in una ciotola e irrorate con un filo di olio e stemperate con acqua calda\u00c2\u00a0 per renderla cremosa.<br \/>\nAiutandovi con una frusta a mano amalgamate gli ingredienti\u00c2\u00a0 ed aggiustate di sale e pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14885\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_172301-e1543651804993-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_172301-e1543651804993-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_172301-e1543651804993-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_172301-e1543651804993-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_172301-e1543651804993-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Unite il composto alla besciamella preparata in predenza e mescolate bene con le fruste a mano per ottenere un composto omogeneo e abbastanza compatto, n\u00c3\u00a8 troppo liquido n\u00c3\u00a8 troppo denso.<\/p>\n<p style=\"text-align: justify;\">Iniziate a<strong> comporre le lasagne:<\/strong> prendete una pirofila dalle dimensioni di 30&#215;20 cm. Irroratela con un filo di olio e versatevi alcuni cucchiai della crema di ricotta e besciamella per corprie il fondo.<br \/>\nAdagiate le sfoglie di pasta fino a ricoprire l\u00e2\u20ac\u2122intera superficie della pirofila.<\/p>\n<p style=\"text-align: justify;\">Poi create un altro strato con la crema di ricotta e besciamella.<br \/>\nDisponete alcune foglioline di timo su tutta la superficie della pirofila ma ben distanziate tra loro\u00c2\u00a0 e cospargete un po\u00e2\u20ac\u2122 di pepe macinato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14954\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_165429-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_165429-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_165429-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_165429-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_165429-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Grattugiate della noce moscata.<br \/>\nCreate un altro strato di lasagne disponendole nel senso opposto rispetto al primo strato in modo che vengano incrociate.<br \/>\nRipetete l&#8217;operazione alternando gli ingredienti fino ad ottenere 6 strati di lasagne, terminando con un ultimo strato di crema di ricotta e besciamella.<\/p>\n<figure id=\"attachment_14886\" aria-describedby=\"caption-attachment-14886\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14886 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_174053-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_174053-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_174053-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_174053-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_174053-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-14886\" class=\"wp-caption-text\">Lasagne alla ricotta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Spolverizzate con abbondante parmigiano grattugiato, aromatizzate ancora con foglioline di timo e pepe macinato e della noce moscata.<br \/>\nInfornate in forno statico preriscaldato a 200\u00c2\u00b0C per 20 minuti (se usate il forno ventilato a 180\u00c2\u00b0C per 10 minuti).<\/p>\n<figure id=\"attachment_14887\" aria-describedby=\"caption-attachment-14887\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14887 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183430-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183430-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183430-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183430-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183430-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-14887\" class=\"wp-caption-text\">Lasagne alla ricotta<\/figcaption><\/figure>\n<figure id=\"attachment_14888\" aria-describedby=\"caption-attachment-14888\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14888 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183442-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183442-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183442-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183442-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/12\/IMG_20181129_183442-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-14888\" class=\"wp-caption-text\">Lasagne alla ricotta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ultimate la cottura in modalit\u00c3\u00a0 grill gli utlimi 2 minuti per creare la leggera crosticina in superficie.<br \/>\nEstraete dal forno le vostre lasagne alla ricotta e lasciate intiepidire 5-6 minuti prima di servire<\/p>\n<p style=\"text-align: justify;\">Anche questa preparazione e&#8217; sparita ma non alla stessa velocita&#8217; delle Lasagne alla Bolognese: quest&#8217;ultima era piu&#8217; &#8220;liquida&#8221; mentre queste lasagne alla ricotta, seppur buone, sono risultate molto piu&#8217; compatte.<\/p>\n<p style=\"text-align: justify;\">Come nella preparazione precedente, e&#8217; stata surgelata e, per riprendersi e scaldarsi, ho impiegato veramente tanto (troppo?) tempo.<\/p>\n<p style=\"text-align: justify;\">Colgo l&#8217;occasione per ringraziare la Ballerina del Nonno, Renata, che ha risposto a tutte le mie assillanti domande:<\/p>\n<div style=\"text-align: justify;\">\n<p><b>LASAGNE<\/b> : Sugo + Grana + Besciamella = Totale 3 strati x 10 persone.<\/p>\n<p><b>TEGLIA<\/b> : 20 x 30 x 4 ( misura interna ) = OK<\/p>\n<p>Se ti servono teglie piu&#8217; ridotte, puoi tagliare la teglia grande e rialzare il bordo cosi&#8217; da ridurre eventualmente il formato in lunghezza.<\/p>\n<p><b>RAGU<\/b> x 10 : 500 Vitello + 500 Manzo + Pelati.<br \/>\nse dovesse avanzare il sugo mettilo in contenitore adatto per il Freezer ( NON di alluminio ).<\/p>\n<p><b>VEGETALE<\/b> :\u00c2\u00a0 400 Spinaci ( gia&#8217; puliti ) + 500 Ricotta + 2 Uova + 100 Grana.<\/p>\n<p><b>ARROSTO<\/b> : Vitello \/ Carne a scelta = 1200 gr<\/p>\n<\/div>\n<p>poi si riduce a 750 gr ( penso sia sufficiente ).&lt;<\/p>\n<p>Puoi surgelarlo da INTERO o gia&#8217; AFFETTATO con il suo SUGO anche in contenitore di Alluminio.<br \/>\nSe il SUGO e&#8217; stato messo a parte per inserirlo dopo, usa un contenitore adatto.<\/p>\n<p><strong>NOTA BENE:<br \/>\n<\/strong>Tutto cio&#8217; che e&#8217; stato surgelato, poi riscaldato e quindi avanzato,<br \/>\n<b>NON VA RISURGELATO<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era prestissimo per il giorno di Natale ma, soprattutto, per pensare al pranzo della Vigilia\/Natale.<\/p>\n","protected":false},"author":2,"featured_media":14888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[],"class_list":["post-14884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/14884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=14884"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/14884\/revisions"}],"predecessor-version":[{"id":24298,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/14884\/revisions\/24298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14888"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=14884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=14884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=14884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}