{"id":1480,"date":"2013-03-27T18:40:00","date_gmt":"2013-03-27T17:40:00","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/buttermilch-sandkuchen\/"},"modified":"2021-04-19T11:12:15","modified_gmt":"2021-04-19T09:12:15","slug":"buttermilch-sandkuchen","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/03\/27\/buttermilch-sandkuchen\/","title":{"rendered":"Buttermilch Sandkuchen"},"content":{"rendered":"<p style=\"text-align: justify;\">Sebbene non capisca nulla di tedesco, mi diverto ugualmente ad andare in biblioteca a prendere in prestito libri di cucina.<!--more--><br \/>\nQuesta ricetta l&#8217;ho provata e ne sono soddisfatta!<\/p>\n<figure id=\"attachment_10057\" aria-describedby=\"caption-attachment-10057\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10057\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6397.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10057\" class=\"wp-caption-text\">ops<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Qui la traduzione (si fa per dire&#8230; GR A\/O ssa RISATA!!!) &#8211; della <strong>BUTTERMILK<\/strong> (latticello) <strong>SANDKUCHEN<\/strong> (torta di sabbia)<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre style=\"text-align: justify;\">100gr burro\r\n 160gr zucchero\r\n 3 uova\r\n 220 g farina\r\n 1\/2 cucchiaino di Bicarbonato (natron)\r\n 1\/2 cucchiaino di lievito di polvere\r\n 250ml di Buttermilch (latticello)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Accendete il forno ventilato a 180Gradi.<\/p>\n<p style=\"text-align: justify;\">Mischiate a crema zucchero e burro.<br \/>\nUnite le uova, una alla volta, sempre mescolando e facendo amalgamare il tutto.<br \/>\nUnite alla farina il bicarbonato ed il lievito, poi unite lentamente questo mix alla crema precedente,<\/p>\n<p style=\"text-align: justify;\">A questo punto aggiungete il latticello.<br \/>\nIn una forma mettete della carta forno (per evitare ulteriore burro).<br \/>\nInfornate per 50 minuti (prova stecchino).<\/p>\n<p style=\"text-align: justify;\">Una volta tolta dal forno, e raffreddata, potrebbe essere anche ricoperta con una glassa al limone: succo di 1\/2 limone con 250gr di zucchero a velo.<\/p>\n<p style=\"text-align: justify;\">Se fate cosi&#8217;, ricordatevi di lasciarla riposare almeno per un&#8217;oretta.. prima di sbranarla!<\/p>\n<figure id=\"attachment_10056\" aria-describedby=\"caption-attachment-10056\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10056\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6398.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10056\" class=\"wp-caption-text\">Buttermilch Sandkuchen<\/figcaption><\/figure>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebbene non capisca nulla di tedesco, mi diverto ugualmente ad andare in biblioteca a prendere in prestito libri di cucina.<\/p>\n","protected":false},"author":2,"featured_media":10056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[183],"class_list":["post-1480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1480"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1480\/revisions"}],"predecessor-version":[{"id":10058,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1480\/revisions\/10058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10056"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}