{"id":1472,"date":"2013-04-07T18:40:00","date_gmt":"2013-04-07T17:40:00","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/frosta-pfanne-asia-curry\/"},"modified":"2023-10-29T15:12:11","modified_gmt":"2023-10-29T14:12:11","slug":"frosta-pfanne-asia-curry","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/04\/07\/frosta-pfanne-asia-curry\/","title":{"rendered":"Frosta &#8211; Pfanne Asia Curry"},"content":{"rendered":"<p style=\"text-align: justify;\">Altro acquisto, altra sorpresa.<!--more--><\/p>\n<p style=\"text-align: justify;\">Gradevole, questa volta.<\/p>\n<p style=\"text-align: justify;\">Nel caso in oggetto si tratta di<\/p>\n<p style=\"text-align: center;\"><strong>Frosta: Pfanne Asia Curry<br \/>\n<\/strong><\/p>\n<figure id=\"attachment_8228\" aria-describedby=\"caption-attachment-8228\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8228\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6354.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8228\" class=\"wp-caption-text\">Frosta &#8211; Pfanne Asia Curry<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si tratta di un mix di verdure, con aggiunta di latte di cocco e un pizzico di curry per insaporire ed\u00c2\u00a0 dare un tocco &#8220;orientale&#8221; ma piacevole al piatto.<\/p>\n<p style=\"text-align: justify;\">Non sapendo bene che cosa avrei potuto trovare all&#8217;interno della confezione\u00c2\u00a0 dopo averlo acquistato o\u00c2\u00a0 cotto (per quanto concerne la sua quantita&#8217; e sapore), lo abbiamo mangiato cosi&#8217; come era.<\/p>\n<p style=\"text-align: justify;\">Sicuramente sarebbe stato meglio abbinarlo con del riso in bianco o essere usato quindi come condimento\/contorno<\/p>\n<figure id=\"attachment_8227\" aria-describedby=\"caption-attachment-8227\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8227\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6353.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8227\" class=\"wp-caption-text\">Frosta &#8211; Pfanne Asia Curry<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altro acquisto, altra sorpresa.<\/p>\n","protected":false},"author":2,"featured_media":8228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[],"class_list":["post-1472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"predecessor-version":[{"id":43158,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1472\/revisions\/43158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8228"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}