{"id":1464,"date":"2013-04-19T18:39:59","date_gmt":"2013-04-19T17:39:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/pasqua\/"},"modified":"2018-09-01T12:51:53","modified_gmt":"2018-09-01T11:51:53","slug":"pasqua_2013","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/04\/19\/pasqua_2013\/","title":{"rendered":"Pasqua 2013"},"content":{"rendered":"<p style=\"text-align: justify;\">Non sono tante le foto che ho scattato quest&#8217;anno a Pasqua&#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Stephan lavorava ed io ho fatto il resto (lavorando a Pasquetta)..<br \/>\nQuindi.. il tempo a disposizione che abbiamo traascorso insieme e&#8217; stato veramente poco.<\/p>\n<p style=\"text-align: justify;\">Ma non avrei potuto non pubblicare la tavola semi-decorata per la colazione:<\/p>\n<figure id=\"attachment_6443\" aria-describedby=\"caption-attachment-6443\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6443 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/9.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/9.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/9-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/9-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-6443\" class=\"wp-caption-text\">Pasqua &#8211; tavola per la colazione<\/figcaption><\/figure>\n<figure id=\"attachment_6444\" aria-describedby=\"caption-attachment-6444\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6444 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-6444\" class=\"wp-caption-text\">Pasqua &#8211; tavola per la colazione<\/figcaption><\/figure>\n<figure id=\"attachment_6442\" aria-describedby=\"caption-attachment-6442\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6442 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/8.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/8.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/8-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/8-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6442\" class=\"wp-caption-text\">Pasqua &#8211; tavola per la colazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ho omesso (perche&#8217; logicamente non scattata) anche quella con tutte le prelibatezze della NOSTRA colazione pasquale, oramai un must:<\/p>\n<p style=\"text-align: justify;\">&#8211; spumante<br \/>\n&#8211; uova sode<br \/>\n&#8211; salame\u00c2\u00a0 (meglio se corallina)<br \/>\n&#8211; caffe&#8217;<br \/>\n&#8211; cioccolato<br \/>\n&#8211; colomba (meglio se pizza di Civitavecchia)<\/p>\n<p style=\"text-align: justify;\">Beh, per noi e&#8217; un&#8217;usanza tramandata dallo zio Nino.<\/p>\n<p style=\"text-align: justify;\">Voi ne avete?<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non sono tante le foto che ho scattato quest&#8217;anno a Pasqua&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[62],"class_list":["post-1464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":12216,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1464\/revisions\/12216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6443"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}