{"id":1453,"date":"2013-05-09T18:39:59","date_gmt":"2013-05-09T17:39:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/bottiglia-per-miscelare\/"},"modified":"2018-11-17T20:37:40","modified_gmt":"2018-11-17T19:37:40","slug":"bottiglia-per-miscelare","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/05\/09\/bottiglia-per-miscelare\/","title":{"rendered":"Bottiglia per miscelare?"},"content":{"rendered":"<p style=\"text-align: justify;\">Su FB avevo visto un&#8217;immagine che mi ha fulminato.<br \/>\nCome sempre (o quasi mi succede), DEVO rifare cio&#8217; che vedo.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">E quindi ri-eccomi all&#8217;opera.<\/p>\n<p style=\"text-align: justify;\">Il problema e&#8217; che da piu&#8217; di un anno, da quando abitiamo qui, i rubinetti della cantina sono separati e l&#8217;acqua e&#8217; fredda-ghiacciata o calda-bollente.<\/p>\n<p style=\"text-align: justify;\">Insomma, non abbiamo ancora risolto questo problema.<\/p>\n<p style=\"text-align: justify;\">O meglio, l&#8217;uomo di casa voleva prendere dei connettori da giardino e raccordarli tra di loro.<\/p>\n<p style=\"text-align: justify;\">Vedendo il risultato (in negozio) tra un raccordo e l&#8217;altro sarebbe stato lungo almeno mezzo metro e avremmo speso una vagonata.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho fatto la prima prova.<\/p>\n<p style=\"text-align: justify;\">Di seguito il risultato:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14571\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6604.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6604.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6604-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6604-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14572\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6608.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6608.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6608-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6608-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14573\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6607.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6607.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6607-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6607-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Il punto negativo e&#8217; che sono TOTALMENTE incostante.<\/p>\n<p style=\"text-align: justify;\">Questa soluzione non e&#8217; naturalmente andata a genio del Signor Perfettino&#8230; che scovera&#8217; qualche cosa di piu&#8217; appropriato.<\/p>\n<p style=\"text-align: justify;\">Da parte mia&#8230; non penso faro&#8217; mai una Release 1.2 , dove il buco di uscita dell&#8217;acqua dovrebbe essere un po&#8217; piu&#8217; arretrato.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su FB avevo visto un&#8217;immagine che mi ha fulminato. Come sempre (o quasi mi succede), DEVO rifare cio&#8217; che vedo.<\/p>\n","protected":false},"author":2,"featured_media":14573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,46],"tags":[94,156],"class_list":["post-1453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-life","tag-diy","tag-lavori"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":14574,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1453\/revisions\/14574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14573"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}