{"id":1411,"date":"2013-08-03T18:39:57","date_gmt":"2013-08-03T17:39:57","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/schultuete-2013\/"},"modified":"2021-04-25T15:15:51","modified_gmt":"2021-04-25T13:15:51","slug":"schultuete-2013","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/08\/03\/schultuete-2013\/","title":{"rendered":"Schult\u00c3\u00bcte 2013"},"content":{"rendered":"<p style=\"text-align: justify;\">Il tempo dell&#8217;asilo e&#8217; quasi terminato, fra poche settimane si iniziera&#8217; una nuova vita scolastica, e questa e&#8217; stata l&#8217;ultima mia creazione ed il mio ultimo sforzo (credo).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Si tratta di &#8216; <strong>Schult\u00c3\u00bcte <\/strong>&#8216; e verra&#8217; utilizzata il 12 settembre, primo giorno di scuola Primaria.<\/p>\n<p style=\"text-align: justify;\">Ma non voglio anticipare ancora che cosa sia, dato che da noi non e&#8217; usanza mentre qui a Patatolandia direi di SIII!!<\/p>\n<figure id=\"attachment_6734\" aria-describedby=\"caption-attachment-6734\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6734\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/5-1.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/5-1.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/5-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/5-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6734\" class=\"wp-caption-text\">schult\u00c3\u00bcte<\/figcaption><\/figure>\n<figure id=\"attachment_6735\" aria-describedby=\"caption-attachment-6735\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6735 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/4-2-e1519154346291.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/4-2-e1519154346291.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/4-2-e1519154346291-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/4-2-e1519154346291-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6735\" class=\"wp-caption-text\">Schult\u00c3\u00bcte<\/figcaption><\/figure>\n<figure id=\"attachment_6736\" aria-describedby=\"caption-attachment-6736\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6736\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/3-5.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/3-5.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/3-5-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/3-5-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-6736\" class=\"wp-caption-text\">schult\u00c3\u00bcte<\/figcaption><\/figure>\n<figure id=\"attachment_6737\" aria-describedby=\"caption-attachment-6737\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6737\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/2-7.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/2-7.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/2-7-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/2-7-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-6737\" class=\"wp-caption-text\">Schult\u00c3\u00bcte<\/figcaption><\/figure>\n<figure id=\"attachment_6738\" aria-describedby=\"caption-attachment-6738\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6738\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1-7.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1-7.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1-7-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1-7-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-6738\" class=\"wp-caption-text\">Schult\u00c3\u00bcte<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Beh, sinceramente mi mancheranno molto i lavoretti fatti, un pizzico di fantasia e l&#8217;uscita dalla solita routines quotidiana, anche per me.<\/p>\n<p style=\"text-align: justify;\">Il ragazzo sta crescendo, e di queste cose non ne vuole quasi piu&#8217; sapere \ud83d\ude41<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tempo dell&#8217;asilo e&#8217; quasi terminato, fra poche settimane si iniziera&#8217; una nuova vita scolastica, e questa e&#8217; stata l&#8217;ultima mia creazione ed il mio ultimo sforzo (credo).<\/p>\n","protected":false},"author":2,"featured_media":6738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,245],"tags":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-istruzione","category-kiga"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":31277,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1411\/revisions\/31277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6738"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}