{"id":1396,"date":"2013-09-05T18:39:57","date_gmt":"2013-09-05T17:39:57","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/che-splendore\/"},"modified":"2018-04-03T19:30:22","modified_gmt":"2018-04-03T18:30:22","slug":"che-splendore","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/09\/05\/che-splendore\/","title":{"rendered":"Che splendore&#8230;"},"content":{"rendered":"<p style=\"text-align: justify;\">Tempo <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/04\/20\/mangold\/\"><strong>fa<\/strong><\/a> avevo trovato del &#8216;mangold&#8217; confezionato e prodotto in Italia.<!--more--><\/p>\n<p style=\"text-align: justify;\">Il suo colore era solo e semplicemente .. VERDE.<\/p>\n<p style=\"text-align: justify;\">Mi chiedevo, infatti, a cosa era dovuto questo nome.<\/p>\n<p style=\"text-align: justify;\">Ora l&#8217;ho capito, soprattutto vedendo questo brillante verde-rosso-giallo_oro sulle foglie della &#8216;stessa&#8217; verdura.<\/p>\n<figure id=\"attachment_10667\" aria-describedby=\"caption-attachment-10667\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10667\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7359-1.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10667\" class=\"wp-caption-text\">Mangold<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Scrivo &#8216;stessa&#8217; anche se, questa volta, non e&#8217; prodotta in Italia, bensi da qui,<\/p>\n<p style=\"text-align: justify;\">Bello, vero?<br \/>\nPeccato che non sia capace di utilizzarlo e di valorizzare le sue tonalita&#8217; al meglio.<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo fa avevo trovato del &#8216;mangold&#8217; confezionato e prodotto in Italia.<\/p>\n","protected":false},"author":2,"featured_media":10666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[],"class_list":["post-1396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1396"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1396\/revisions"}],"predecessor-version":[{"id":10668,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1396\/revisions\/10668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10666"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}