{"id":12882,"date":"2018-10-05T10:16:58","date_gmt":"2018-10-05T09:16:58","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=12882"},"modified":"2019-07-26T13:52:00","modified_gmt":"2019-07-26T12:52:00","slug":"civilta-scale-mobili","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/10\/05\/civilta-scale-mobili\/","title":{"rendered":"Civilta&#8217;: scale mobili"},"content":{"rendered":"<p>Sempre sulla scia dell &#8220;Oktoberfest&#8221; ho notato una terribile mancanza di civilta&#8217; da parte della stragrande maggioranza degli stranieri in visita.<\/p>\n<p><!--more--><\/p>\n<p>Si tratta del banale uso della SCALA MOBILE.<\/p>\n<figure id=\"attachment_12883\" aria-describedby=\"caption-attachment-12883\" style=\"width: 144px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12883 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/scala.jpg\" alt=\"\" width=\"144\" height=\"160\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/scala.jpg 144w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/scala-135x150.jpg 135w\" sizes=\"auto, (max-width: 144px) 100vw, 144px\" \/><figcaption id=\"caption-attachment-12883\" class=\"wp-caption-text\">Tratta da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Lo so che, ultimamente, sto diventando una vecchia pedante ma, vivendo in qualsiasi parte del mondo, si finisce per adottare gli usi e costumi locali, soprattutto se si tratta di situazioni semplici da risolvere.<\/p>\n<p style=\"text-align: justify;\">Nel nostro caso Patatolese, le scale mobili vengono usate per _salire_ al piano superiore, ma anche per scendere.<br \/>\nSeguendo la corretta indicazione di marcia.<\/p>\n<p style=\"text-align: justify;\">E&#8217;<strong> BUONA NORMA<\/strong> mantenersi sul lato <strong>DESTRO<\/strong> del corrimano, lasciando la &#8220;corsia&#8221; SINISTRA libera.<br \/>\nCosi&#8217; facendo, per chi e&#8217; di fretta, puo&#8217; sempre essere avvantagiato nella corsa in salita ( o in discesa, a seconda dei casi ) e non essere intralciato dalle persone che non hanno la necessita&#8217; di affrettarsi.<br \/>\nSi tratta, un po&#8217;, come una corsia dedicata al sorpasso.<\/p>\n<p style=\"text-align: justify;\">Quindi, se vi dovesse capitare di passare di qui&#8230; mantenete la vostra posizione e NON state al centro della scala mobile.<br \/>\nNon so bene come sia da voi, non ricordo molto di com&#8217;era a Milano prima del mio trasferimento, ma cercate di non essere di intralcio per i locali.<\/p>\n<figure id=\"attachment_12884\" aria-describedby=\"caption-attachment-12884\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12884 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/londra-1.jpg\" alt=\"\" width=\"800\" height=\"366\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/londra-1.jpg 800w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/londra-1-150x69.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/londra-1-300x137.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/09\/londra-1-768x351.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-12884\" class=\"wp-caption-text\">Presa da Internet: Pendolari alla stazione di Angel, a Londra. (Dan Kitwood\/Getty Images)<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sempre sulla scia dell &#8220;Oktoberfest&#8221; ho notato una terribile mancanza di civilta&#8217; da parte della stragrande maggioranza degli stranieri in visita.<\/p>\n","protected":false},"author":2,"featured_media":12883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,164],"tags":[140],"class_list":["post-12882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monaco","category-varie","tag-civilta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/12882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=12882"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/12882\/revisions"}],"predecessor-version":[{"id":12885,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/12882\/revisions\/12885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12883"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=12882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=12882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=12882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}