{"id":1271,"date":"2014-06-03T18:39:50","date_gmt":"2014-06-03T17:39:50","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/topi-ad-amburgo\/"},"modified":"2018-03-06T09:26:51","modified_gmt":"2018-03-06T08:26:51","slug":"topi-ad-amburgo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2014\/06\/03\/topi-ad-amburgo\/","title":{"rendered":"Pasta con &#8220;Topi ad Amburgo&#8221;"},"content":{"rendered":"<p>Cosi&#8217; li chiamiamo a casa nostra\u00c2\u00a0\u00c2\u00a0 \ud83d\ude42<!--more-->In effetti si tratta dei &#8220;TOPINAMBUR&#8221; un tubero molto saporito, un gusto tra la patata ed il carciofo.<\/p>\n<p>Avevo acquistato qualche giorno fa dei topinambur, ma non avevo idea di come cucinarli.<\/p>\n<p style=\"text-align: justify;\">\nCosi&#8217;, &#8220;sfogliando&#8221; tra i vari Blog, ho trovato il suggerimento del Cavoletto.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>olio\r\naglio\r\nacciughe\r\ntopinambur\r\npasta<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una padella scadate dell&#8217;olio con dello scalogno (liofilizzato!!\u00c2\u00a0 quando si suggeriva dell&#8217;aglio).<br \/>\nAggiungete della pasta di acciughe (non avevo le acciughe) e, per ultimo, i topinambur tagliati fini-fini.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo mettere a cuocere delle linguine<br \/>\nAggiungete qualche cucchiaiata di acqua di cottura nella verdura in cottura e, una volta pronta la pasta, scolata e scaldatela assieme al mix di verdura, con abbondante prezzemolo.<\/p>\n<p style=\"text-align: justify;\">Un piatto semplice ma, per il suo volume, ha appagato la vista e lo stomaco.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8318\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/zobna-miska.jpg\" alt=\"\" width=\"286\" height=\"262\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/zobna-miska.jpg 286w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/zobna-miska-150x137.jpg 150w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosi&#8217; li chiamiamo a casa nostra\u00c2\u00a0\u00c2\u00a0 \ud83d\ude42<\/p>\n","protected":false},"author":2,"featured_media":8318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[],"class_list":["post-1271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1271"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1271\/revisions"}],"predecessor-version":[{"id":8319,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1271\/revisions\/8319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8318"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}