{"id":1251,"date":"2014-07-30T18:39:49","date_gmt":"2014-07-30T17:39:49","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/mymusli-2go\/"},"modified":"2018-11-15T19:42:01","modified_gmt":"2018-11-15T18:42:01","slug":"mymusli-2go","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2014\/07\/30\/mymusli-2go\/","title":{"rendered":"Mymusli 2go"},"content":{"rendered":"<p style=\"text-align: justify;\">Sono pazza, ma questi musly li ho voluti proprio provare.<br \/>\nHo atteso un (bel) po&#8217; prima di prendere coraggio e un&#8217;offerta\u00c2\u00a0 abbastanza conveniente sul prezzo di acquisto.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Perche&#8217;?<\/p>\n<p style=\"text-align: justify;\">Perche&#8217; questi<a href=\"http:\/\/mymuesli2go.com\/\"> <em>Mymusli2go<\/em>\u00c2\u00a0<\/a> sono _TOTALMENTE_ costosi (se seguite il link avrete un piccolo esempio).<\/p>\n<figure id=\"attachment_14193\" aria-describedby=\"caption-attachment-14193\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-14193\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_1149-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_1149-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_1149-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_1149-225x300.jpg 225w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_1149.jpg 1200w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-14193\" class=\"wp-caption-text\">Mymusli 2to<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In effetti non sono per nulla malacci, ma non li acquistero&#8217; poi cosi&#8217; spesso (dato il prezzo).<br \/>\nSono veramente ricchi ed assortiti di frutta disidratata e, una volta aggiunto il latte (nel mio caso), non risulta immediatamente il solito pastone\/pappone che proprio non riesco a mangiare.<\/p>\n<p style=\"text-align: justify;\">Magari sarebbe piu&#8217; conveniente acquistare i singoli prodotti e farli a casa,ma anche presi gli ingredienti singolarmente non sono cosi&#8217; economici.<\/p>\n<p style=\"text-align: justify;\">Ancora una volta, pero&#8217; mi sono stupita delle indicazioni fornite dai prodotti BIO.<br \/>\nIn pratica&#8230; non esistono!<\/p>\n<p style=\"text-align: justify;\">Sulla confezione MANCA totalmente ogni minima indicazione sulla percentuale degli ingredienti che lo compongono, ed anche se seno BIO (o altro).<br \/>\nA posteriori su Internet si trova qualche cosa, ma dovrei cercare PRIMA!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono pazza, ma questi musly li ho voluti proprio provare. Ho atteso un (bel) po&#8217; prima di prendere coraggio e un&#8217;offerta\u00c2\u00a0 abbastanza conveniente sul prezzo di acquisto.<\/p>\n","protected":false},"author":2,"featured_media":14193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,22],"tags":[],"class_list":["post-1251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1251"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1251\/revisions"}],"predecessor-version":[{"id":14194,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1251\/revisions\/14194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14193"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}