{"id":1208,"date":"2015-02-03T18:39:47","date_gmt":"2015-02-03T17:39:47","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/3-febbraio-san-biagio\/"},"modified":"2018-11-05T18:33:44","modified_gmt":"2018-11-05T17:33:44","slug":"san-biagio-2015","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/02\/03\/san-biagio-2015\/","title":{"rendered":"3 Febbraio &#8211; San Biagio"},"content":{"rendered":"<p style=\"text-align: justify;\">Come vuole la tradizione milanese, a San Biagio bisogna mangiare il panettone (benedetto).<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Il mio non era molto benedetto, ma poco importa.<\/p>\n<p style=\"text-align: justify;\">Non interessara&#8217; molto al Biagio che lo abbiamo aperto ieri&#8230; e continuato oggi.<\/p>\n<p style=\"text-align: justify;\">Di sicuro, con la temperatura di questa mattina, una fetta salutare per la gola ci stava proprio bene.<br \/>\nQui il mio ragazzo in uscita da casa<\/p>\n<figure id=\"attachment_13264\" aria-describedby=\"caption-attachment-13264\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13264 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/IMG_20150203_072738-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/IMG_20150203_072738-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/IMG_20150203_072738-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/IMG_20150203_072738-225x300.jpg 225w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/IMG_20150203_072738.jpg 1200w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-13264\" class=\"wp-caption-text\">Il mio pinguino<\/figcaption><\/figure>\n<figure id=\"attachment_13262\" aria-describedby=\"caption-attachment-13262\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13262 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/10959574_10152826426503692_4079261281227558868_n.jpg\" alt=\"\" width=\"960\" height=\"600\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/10959574_10152826426503692_4079261281227558868_n.jpg 960w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/10959574_10152826426503692_4079261281227558868_n-150x94.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/10959574_10152826426503692_4079261281227558868_n-300x188.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/02\/10959574_10152826426503692_4079261281227558868_n-768x480.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-13262\" class=\"wp-caption-text\">Temperatura dal Tablet<\/figcaption><\/figure>\n<p>Qui un poco del perche&#8217;:<\/p>\n<p style=\"text-align: justify;\"><strong>Ma chi era San Biagio?\u00c2\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">La storia parte da molto lontano. Intorno al 300 D.C. Biagio Nacque in Armenia, e fece il medico fino a quando la popolazione delle sua citt\u00c3\u00a0 non lo spinse a fare il vescovo, non dimenticando per\u00c3\u00b2 la sua professione. Da vescovo curava le anime e da medico il corpo. Fino a quando un giorno una madre disperata, si present\u00c3\u00b2 al suo cospetto perch\u00c3\u00a9 il figlio aveva una lisca di pesce conficcata in gola. L\u00e2\u20ac\u2122istinto di medico gli fece usare della mollica di pane e la fede di vescovo la fece mangiare al ragazzo solo dopo averla benedetta. Il metodo che aveva ben poco di miracoloso gli fece salvare la vita del ragazzo.<br \/>\nMa la notizia del miracolo fece presto molta strada e questo non piacque ad Agricola, prefetto di Diocleziano per l\u00e2\u20ac\u2122Armenia. E sentendo crescere a dismisura la fama di Biagio, decise con una scusa di convocare il vescovo, e trovandoselo davanti lo fece uccidere, per evitare la santificazione da parte del popolo. Ma il martirio ottenne l\u00e2\u20ac\u2122effetto contrario, e presto Biagio fu fatto Santo.<\/p>\n<p style=\"text-align: justify;\">E in ricordo dell\u00e2\u20ac\u2122episodio del bambino e della mollica, il 3 febbraio si usa mangiare del pane benedetto per proteggere la gola.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come vuole la tradizione milanese, a San Biagio bisogna mangiare il panettone (benedetto).<\/p>\n","protected":false},"author":2,"featured_media":13262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-1208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1208"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1208\/revisions"}],"predecessor-version":[{"id":13265,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1208\/revisions\/13265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13262"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}