{"id":1179,"date":"2015-03-18T18:39:46","date_gmt":"2015-03-18T17:39:46","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/colomba-1-0\/"},"modified":"2018-04-30T10:01:34","modified_gmt":"2018-04-30T09:01:34","slug":"colomba-1-0","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/03\/18\/colomba-1-0\/","title":{"rendered":"Colomba Giorilli &#8211; 1.0"},"content":{"rendered":"<p style=\"text-align: justify;\">Ho voluto tentare questa impresa faraonica&#8230;<!--more--><\/p>\n<p style=\"text-align: justify;\">la preparazione della Colomba fatta in casa.<\/p>\n<p style=\"text-align: justify;\">In effetti, per preparare la colomba ho impiegato molto piu&#8217; tempo del previsto.<br \/>\nSoprattutto per la lievitazione che non ne voleva sapere affatto di iniziare, devo dire che e&#8217; il tempo trascorso in attesa e&#8217; stato piu&#8217; lungo che durante il mio parto.<\/p>\n<p style=\"text-align: justify;\">Non contenta, questo fine settimana replichero&#8217;.<\/p>\n<p style=\"text-align: justify;\">Ho visto alcuni errori durante il MIO procedimento, quindi vorrei riprovare, e tentare nuovamente la sorte<\/p>\n<p style=\"text-align: justify;\">Spero solo di non passare nuovamente 2 notti in bianco!<\/p>\n<p style=\"text-align: justify;\">La ricetta usata e&#8217; quella di <a href=\"http:\/\/blog.giallozafferano.it\/fablesucre\/colomba-di-giorilli\/\">Giorilli, <\/a>ma ho integrato le informazioni con altri dati trovati in giro per la rete.<\/p>\n<p style=\"text-align: justify;\">E questi alcuni risultati ottenuti.<\/p>\n<figure id=\"attachment_6449\" aria-describedby=\"caption-attachment-6449\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6449 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/x-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6449\" class=\"wp-caption-text\">Con l&#8217;avanzo dell&#8217;impasto ho creato queste tortine&#8230; deliziose!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Non ho fotografato tutto il procedimento, essendo molto nervosa sulla sua riuscita ma\/e soprattutto nel capire se andava bene.<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, qui alcune immagini<\/p>\n<figure id=\"attachment_6450\" aria-describedby=\"caption-attachment-6450\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6450 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/z-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6450\" class=\"wp-caption-text\">Colomba &#8211; Prima della lievitazione<\/figcaption><\/figure>\n<figure id=\"attachment_6448\" aria-describedby=\"caption-attachment-6448\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6448 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-1-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6448\" class=\"wp-caption-text\">Colomba &#8211; Lo so, non sono lievitate molto, ma non ce la facevo piu&#8217;<\/figcaption><\/figure>\n<figure id=\"attachment_6447\" aria-describedby=\"caption-attachment-6447\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6447 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/v-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6447\" class=\"wp-caption-text\">Ribaltamento per asciugatura.. una colomba si e&#8217; spezzata \ud83d\ude41<\/figcaption><\/figure>\n<figure id=\"attachment_6446\" aria-describedby=\"caption-attachment-6446\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6446 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/b-1-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6446\" class=\"wp-caption-text\">Colomba: il risultato finale<\/figcaption><\/figure>\n<p>Colomba &#8211; Prima della lievitazione<\/p>\n<p style=\"text-align: justify;\">La prima colomba &#8211; spezzata &#8211; e&#8217; stata gia&#8217; aperta.<br \/>\nVeramente buona, con i canditi all&#8217;interno.<\/p>\n<p style=\"text-align: justify;\">La seconda, sempre che sopravviva, verra&#8217; aperta a Pasqua.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho voluto tentare questa impresa faraonica&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,144,90],"tags":[153,112,62],"class_list":["post-1179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-grandi","category-lievitati","tag-homemade","tag-licoli","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1179"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1179\/revisions"}],"predecessor-version":[{"id":6452,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1179\/revisions\/6452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6448"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}