{"id":1178,"date":"2019-03-19T18:39:46","date_gmt":"2019-03-19T17:39:46","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/festa-del-papa-3\/"},"modified":"2019-01-03T17:41:30","modified_gmt":"2019-01-03T16:41:30","slug":"festa-papa-2019","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/03\/19\/festa-papa-2019\/","title":{"rendered":"Festa del papa&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Come i piu&#8217; attenti seguaci di Patatolandia sapranno, la <strong>festa del papa&#8217;<\/strong> non viene festeggiata a marzo, bensi&#8217; a maggio.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">In questo giorno, infatti, tutti i negozi sono chiusi e, pare, i padri di famiglia &#8216;scappano&#8217; da casa per trovarsi tutti insieme al Biergarten e.. attenzione, attenzione&#8230; farsi una bella birra.<\/p>\n<p style=\"text-align: justify;\">E qui a casa nostra?<\/p>\n<p style=\"text-align: justify;\">Ogni tanto mi ricordo di festeggiare Stephan ma, onestamente, non sono poche le volte che lo scordo &#8211; o semplicemente non ho tempo &#8211; per preparare qualche cosa per noi<\/p>\n<p style=\"text-align: justify;\">Ma gli auguri a voce si fanno sempre!<\/p>\n<figure id=\"attachment_14750\" aria-describedby=\"caption-attachment-14750\" style=\"width: 350px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14750\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/auguri_papi.gif\" alt=\"\" width=\"350\" height=\"300\" \/><figcaption id=\"caption-attachment-14750\" class=\"wp-caption-text\">Tratta dal Web<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come i piu&#8217; attenti seguaci di Patatolandia sapranno, la festa del papa&#8217; non viene festeggiata a marzo, bensi&#8217; a maggio.<\/p>\n","protected":false},"author":2,"featured_media":14750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[123],"class_list":["post-1178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-festa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"predecessor-version":[{"id":15369,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1178\/revisions\/15369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14750"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}