{"id":11645,"date":"2018-08-01T17:58:31","date_gmt":"2018-08-01T16:58:31","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=11645"},"modified":"2019-12-16T11:15:07","modified_gmt":"2019-12-16T10:15:07","slug":"caldo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/08\/01\/caldo\/","title":{"rendered":"&#8230; caldo..!"},"content":{"rendered":"<p style=\"text-align: justify;\">Ebbene si, non pensiate di essere gli unici al caldo!<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Anche noi, in questi giorni, ci difendiamo bene con le alte temperature.<\/p>\n<p style=\"text-align: justify;\">E questa e&#8217; una immagine della situazione attuale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11646\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/08\/caldo.jpg\" alt=\"\" width=\"898\" height=\"632\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/08\/caldo.jpg 898w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/08\/caldo-150x106.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/08\/caldo-300x211.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/08\/caldo-768x541.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\">Oggi abbiamo toccato i 34-37 gradi.<br \/>\nSituazione che, almeno qui a Patatolandia, e&#8217; molto insolita.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ebbene si, non pensiate di essere gli unici al caldo!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110],"tags":[],"class_list":["post-11645","post","type-post","status-publish","format-standard","hentry","category-monaco"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=11645"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11645\/revisions"}],"predecessor-version":[{"id":11647,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11645\/revisions\/11647"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=11645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=11645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=11645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}