{"id":11550,"date":"2018-08-23T09:53:34","date_gmt":"2018-08-23T08:53:34","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=11550"},"modified":"2021-03-02T17:47:51","modified_gmt":"2021-03-02T16:47:51","slug":"oryza-basmati-reis","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/08\/23\/oryza-basmati-reis\/","title":{"rendered":"Oryza: Basmati reis &#8211; Kokos, Zitronengras"},"content":{"rendered":"<p style=\"text-align: justify;\">I tempi di preparazione per pranzo\/cena sono stretti?<\/p>\n<p style=\"text-align: justify;\">Avete pensato ad un secondo ma vi servirebbe un carboidrato di accompagnamento?<!--more--><\/p>\n<p style=\"text-align: justify;\">Perche&#8217; non cuocere al microonde un riso veloce?<\/p>\n<p style=\"text-align: justify;\">Detto.. fatto!<\/p>\n<figure id=\"attachment_11551\" aria-describedby=\"caption-attachment-11551\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11551 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/07\/IMG_9814-e1532802853781-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/07\/IMG_9814-e1532802853781-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/07\/IMG_9814-e1532802853781-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/07\/IMG_9814-e1532802853781-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/07\/IMG_9814-e1532802853781-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-11551\" class=\"wp-caption-text\">Oryza &#8211; Basmati reis &#8211; Kocos e Zitronengras<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con questa busta di riso basmati &#8220;<strong>Oryza &#8211; Kokos Zitronengras<\/strong>&#8221; , cotto velocemente in 2 minuti nel microonde, vi troverete subito circondati da un aroma di cocco e citronella che si espandera&#8217; ed inondera&#8217; la cucina.<\/p>\n<p style=\"text-align: justify;\">Certo, con un arrosto non ci sta molto bene&#8230;<br \/>\nForse e&#8217; meglio accompagnare un petto di pollo cotto velocemente alla piastra, magari aggiungendo una veloce salsa allo yoghurt come accompagnamento.<\/p>\n<p style=\"text-align: justify;\">Oppure delle verdure saltate e speziate &#8220;all&#8217;orientale&#8221;&#8230;<\/p>\n<p>Diciamo che le preparazioni sono tante, non limitatevi!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I tempi di preparazione per pranzo\/cena sono stretti? Avete pensato ad un secondo ma vi servirebbe un carboidrato di accompagnamento?<\/p>\n","protected":false},"author":2,"featured_media":11551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,67],"tags":[],"class_list":["post-11550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-riso_risotti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=11550"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11550\/revisions"}],"predecessor-version":[{"id":11980,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11550\/revisions\/11980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/11551"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=11550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=11550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=11550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}