{"id":1152,"date":"2015-04-23T18:39:45","date_gmt":"2015-04-23T17:39:45","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/agnello-pasquale\/"},"modified":"2018-03-07T17:18:33","modified_gmt":"2018-03-07T16:18:33","slug":"agnello-pasquale","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/04\/23\/agnello-pasquale\/","title":{"rendered":"Agnello Pasquale"},"content":{"rendered":"<p style=\"text-align: justify;\">In Italia il piu&#8217; comune dolce durante il periodo della Pasqua e&#8217; sicuramente la Colomba.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Anche se ho appena visto che esistono altri dolci caratteristici al Sud Italia, fatta prevalentemente con pasta di mardorle o affine..<\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia esiste l&#8217;agnello, che non e&#8217; altro che una torta cotta nello stampo di questo animale &#8211; appunto &#8211; e gli contribuisce questa forma.<\/p>\n<figure id=\"attachment_6460\" aria-describedby=\"caption-attachment-6460\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6460\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/q-1.jpg\" alt=\"\" width=\"1200\" height=\"1600\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/q-1.jpg 1200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/q-1-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/q-1-225x300.jpg 225w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/q-1-768x1024.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6460\" class=\"wp-caption-text\">Agnello fatto da Sandra<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quest&#8217;anno abbiamo ricevuto diversi &#8220;agnelli di pasqua&#8221; in regalo, logicamente fatti in casa.<\/p>\n<p>Sicuramente l&#8217;agnello piu&#8217; degno di nota e&#8217; quella di Sandra, che ha deciso di coprire le nudita&#8217; del piccolo agnellino con marshmellow!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Italia il piu&#8217; comune dolce durante il periodo della Pasqua e&#8217; sicuramente la Colomba.<\/p>\n","protected":false},"author":2,"featured_media":6460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[62],"class_list":["post-1152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":6461,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1152\/revisions\/6461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6460"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}