{"id":11441,"date":"2018-06-29T10:29:58","date_gmt":"2018-06-29T09:29:58","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=11441"},"modified":"2018-06-29T10:29:58","modified_gmt":"2018-06-29T09:29:58","slug":"pie-chart","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/06\/29\/pie-chart\/","title":{"rendered":"Pie Chart"},"content":{"rendered":"<p>Tobias ha preparato una ricerca con alcuni suoi compagni di classe.<!--more--><\/p>\n<p>Parte del risultato doveva essere evidenziato con un grafico &#8220;a torta&#8221;.<\/p>\n<p>Ecco quindi la sua geniale idea&#8230; fare una TORTA con il grafico impresso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11442\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/06\/IMG_20180624_095625-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/06\/IMG_20180624_095625-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/06\/IMG_20180624_095625-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/06\/IMG_20180624_095625-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/06\/IMG_20180624_095625-768x576.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Diciamo che non e&#8217; venuta estramamente bene&#8230; ma ci si accontenta.<\/p>\n<p style=\"text-align: justify;\">Ho usato 2 confezioni di torta al limone in scatola,\u00c2\u00a0 facendole cuocere in una teglia rettangolare per circa 25 minuti.<\/p>\n<p style=\"text-align: justify;\">La torta e&#8217; stata poi tagliata e farcita con crema al mascarpone, zucchero a velo e philadelphia.<br \/>\nNon chiedetemi le quantita&#8217;.. sono andata ad occhio!<br \/>\nE&#8217; stata poi stuccata con burro e zucchero prima di essere coperta da fondente.<\/p>\n<p style=\"text-align: justify;\">A quanto pare la sua insegnante non aveva mai ricevuto una torta simile come risultato da una ricerta \ud83d\ude42<br \/>\nInutile aggiungere che e&#8217; piaciuta anche alla classe, definendola &#8220;leggendaria&#8221;.<\/p>\n<p>Beh.. pure queste sono soddisfazioni<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tobias ha preparato una ricerca con alcuni suoi compagni di classe.<\/p>\n","protected":false},"author":2,"featured_media":11442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[118],"class_list":["post-11441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-istruzione","tag-pdz"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=11441"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11441\/revisions"}],"predecessor-version":[{"id":11445,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11441\/revisions\/11445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/11442"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=11441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=11441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=11441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}