{"id":11238,"date":"2018-05-23T11:54:25","date_gmt":"2018-05-23T10:54:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=11238"},"modified":"2019-04-25T19:13:42","modified_gmt":"2019-04-25T18:13:42","slug":"pan-di-panna","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/05\/23\/pan-di-panna\/","title":{"rendered":"Pan di Panna"},"content":{"rendered":"<p style=\"text-align: justify;\">Anche questa ricetta di &#8220;Pan di Panna&#8221;\u00c2\u00a0 impazza nel Web.<\/p>\n<p style=\"text-align: justify;\">Il mio tentativi e risultato a casa nostra &#8230; non si e&#8217; fatto attendere!<!--more--><\/p>\n<p style=\"text-align: justify;\">Le indicazioni sono sul sito di <a href=\"https:\/\/aniceecannella.blogspot.de\/2018\/04\/il-pan-di-panna.html?m=1\">Aniceecannella<\/a>, ma copio gli ingredienti ed il procedimento originale<\/p>\n<figure id=\"attachment_11299\" aria-describedby=\"caption-attachment-11299\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11299 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8720-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8720-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8720-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8720-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8720-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-11299\" class=\"wp-caption-text\">Pan di Panna<\/figcaption><\/figure>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre>600 gr di farina W280\/W330 (ho usato la caputo rossa)\r\n 1 uovo\r\n 250 gr di latte\r\n 100 gr di panna fresca\r\n 10 gr di sale\r\n 80 gr di zucchero\r\n 25 gr di burro (da sciogliere nel latte)\r\n 10 gr di lievito di birra fresco\r\n\r\nPer la <strong>spennellatura finale<\/strong>\r\n1 tuorlo  \r\n1 cucchiaio di panna\r\n1 pizzico di sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Versate nella ciotola dell&#8217;impastatrice il latte col burro sciolto (ovviamente fatto raffreddare),\u00c2\u00a0 1 uovo,\u00c2\u00a0 20 gr dello zucchero previsto e il lievito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11296\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8716-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8716-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8716-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8716-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8716-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mescolate per pochissimi secondi con la foglia, poi aggiungete farina quanto basta a formare una massa morbida ma sostenuta, poi alternate in 3 volte, e in questa sequenza 1\/3 della panna\/1\/3 dello zucchero\/farina quanto basta a riportare l&#8217;impasto in corda.<\/p>\n<p style=\"text-align: justify;\">Ribaltate ogni tanto l&#8217;impasto in ciotola.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11297\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8717-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8717-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8717-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8717-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8717-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Terminate con l&#8217;ultima farina rimasta, quindi aggiungete il sale e incordate l&#8217;impasto, ribaltando due o tre volte.<\/p>\n<p style=\"text-align: justify;\">Fate riposare 1h coperto, poi piegate a 3 per ottenere un rettangolo (NON fare una piega completa!) e riposo 20&#8242;.<\/p>\n<p style=\"text-align: justify;\">Spezzate l&#8217;impasto in pezzi rettangolari da 90 gr allungali delicatamente col mattarello (aiutandovi con poca farina) e avvolgeteli su se stessi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11298\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8718-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8718-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8718-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8718-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8718-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><em>Come potete vedere dalle immagini, per facilitarmi, ho fatto delle palline \ud83d\ude42<\/em><\/p>\n<p style=\"text-align: justify;\">Mettete i pezzi formati in una teglia 30&#215;40 cm. coperta da carta forno.<br \/>\nLasciate raddoppiare coperto con pellicola e infornate, dopo aver spennellato, a 180\u00c2\u00b0 fino a doratura.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Per la formatura:<\/strong><\/em> ho fatto delle palline di circa 75gr cad (l&#8217;impasto totale risulta essere poco piu&#8217; di 1kg).<\/p>\n<p style=\"text-align: justify;\"><em><strong>Per la spennellatura<\/strong><\/em> ho usato solamente panna.<\/p>\n<figure id=\"attachment_11300\" aria-describedby=\"caption-attachment-11300\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11300 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8725-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8725-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8725-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8725-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/05\/IMG_8725-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-11300\" class=\"wp-caption-text\">Pan di Panna<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Purtroppo non l&#8217;ho lasciato cuocere perfettamente.<br \/>\nL&#8217;interno era un po&#8217; crudo, soprattutto nelle palline al centro.<\/p>\n<p style=\"text-align: justify;\">Onestamente.. non e&#8217; che mi\/ci sia piaciuto particolarmente&#8230; la causa sara&#8217; stata forse la poco cottura?<br \/>\nTanto e&#8217; vero che non mi e&#8217; risultato particolarmente soffice.<\/p>\n<p style=\"text-align: justify;\">Al momento preferisco ancora il &#8220;<a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/09\/23\/paoletta-sersante\/\">Quattro e quattr&#8217;otto<\/a>&#8221; di Paoletta.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche questa ricetta di &#8220;Pan di Panna&#8221;\u00c2\u00a0 impazza nel Web. Il mio tentativi e risultato a casa nostra &#8230; non si e&#8217; fatto attendere!<\/p>\n","protected":false},"author":2,"featured_media":11300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145,22,90],"tags":[116],"class_list":["post-11238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolci","category-food","category-lievitati","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=11238"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11238\/revisions"}],"predecessor-version":[{"id":16672,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/11238\/revisions\/16672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/11300"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=11238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=11238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=11238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}