{"id":1103,"date":"2015-06-10T18:39:43","date_gmt":"2015-06-10T17:39:43","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-di-asparagi\/"},"modified":"2019-11-28T09:06:12","modified_gmt":"2019-11-28T08:06:12","slug":"torta-di-asparagi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/06\/10\/torta-di-asparagi\/","title":{"rendered":"Torta salata di asparagi"},"content":{"rendered":"<p style=\"text-align: justify;\">Veramente MOLTO veloce la preparazione di questa &#8220;<em><strong>torta salata di asparagi e pomodorini<\/strong><\/em>&#8220;: sia in nel tempo di cottura che nel tempo impiegato nel terminarla&#8230; a MANGIARE!<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nUn battito d&#8217;ali, come si dice.<\/p>\n<p style=\"text-align: justify;\">La ricetta l&#8217;ho vista<strong><em><a href=\"https:\/\/migusto.migros.ch\/it\/ricette\/torta-di-asparagi-e-pomodori\" target=\"_blank\" rel=\"noopener\"> qui<\/a><\/em><\/strong> ( ex &#8220;Cucina di Stagione&#8221; ) e le uniche modifiche fatte (dettate dal non facile reperimento degli ingredienti):<br \/>\n&#8211; taleggio\u00c2\u00a0 &#8230;con&#8230; altro formaggio molto simile alla fontina<br \/>\n&#8211; pasta di olive\u00c2\u00a0 &#8230;con&#8230; pasta di noci<\/p>\n<figure id=\"attachment_8358\" aria-describedby=\"caption-attachment-8358\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8358\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2600.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8358\" class=\"wp-caption-text\">Torta salata di asparagi<\/figcaption><\/figure>\n<p>Copia-Incolla dal sito<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre>1 sfoglia Rustico rettangolare gi\u00c3\u00a0 spianata di 320\r\n4 cucchiaini di pasta d\u00e2\u20ac\u2122olive nere\r\n500 g di asparagi verdi\r\n80 g di pomodori secchi sott\u00e2\u20ac\u2122olio, ad es. pomodori cherry\r\n100 g di taleggio\r\npepe\r\n2 rametti di maggiorana<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Scaldate il forno a 220 \u00c2\u00b0C.<\/p>\n<p style=\"text-align: justify;\">Srotolate la pasta e accomodatela su una placca da forno capovolta con la carta da forno.<br \/>\nSpalmate la pasta di olive sulla pasta lasciando libero un bordo di ca. 1 cm.<\/p>\n<p style=\"text-align: justify;\">Pelate il terzo inferiore degli asparagi e spuntateli. Dimezzate gli asparagi per il lungo, metteteli in una scodella e mescolate con poco olio dei pomodori. Tagliate il taleggio a dadini.<\/p>\n<p style=\"text-align: justify;\">Accomodate gli asparagi e i pomodori sulla pasta.<br \/>\nCondite con il pepe.<\/p>\n<p style=\"text-align: justify;\">Cuocete la torta al centro del forno per ca. 10 minuti.<br \/>\nDue minuti prima di fine cottura, distribuite il formaggio sulla torta e terminate la cottura.<br \/>\nSfornate, guarnite con le foglie di maggiorana e servite.<\/p>\n<p style=\"text-align: justify;\">Direi che e&#8217; un&#8217;ottima soluzione ed approccio per un pranzo veloce, o come aperitivo.<br \/>\nLa verdura, in questo caso, e&#8217; restata croccante ma non cruda.<\/p>\n<p>Magari combinando e cambiando gli ingredienti, ottenendo cosi&#8217; nuovi sapori.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veramente MOLTO veloce la preparazione di questa &#8220;torta salata di asparagi e pomodorini&#8220;: sia in nel tempo di cottura che nel tempo impiegato nel terminarla&#8230; a MANGIARE!<\/p>\n","protected":false},"author":2,"featured_media":8358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,138],"tags":[],"class_list":["post-1103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-piatti_unici"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1103"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1103\/revisions"}],"predecessor-version":[{"id":19155,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1103\/revisions\/19155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8358"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}