{"id":1094,"date":"2015-06-19T18:39:43","date_gmt":"2015-06-19T17:39:43","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/fiori-di-sambuco\/"},"modified":"2023-03-04T15:17:29","modified_gmt":"2023-03-04T14:17:29","slug":"fiori-di-sambuco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/06\/19\/fiori-di-sambuco\/","title":{"rendered":"Fiori di Sambuco!"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;altra domenica da Oma ho raccolto un bel mazzo di fiori di sambuco.<\/p>\n<p>Ho poi scoperto che tutta la stragrande maggioranza della strada era invasa da queste piante!<br \/>\nMa quanto sono ignorante, spesso&#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">I fiori di sambuco hanno un profumo particolare, che ha inondato la macchina durante il nostro rientro.<br \/>\nE non solo!<br \/>\nAnche la casa e&#8217; stata invasa da questo gradevole aroma, per alcuni giorni&#8230; fino alla preparazione di una <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/06\/20\/frittata-ai-fiori-di-sambuco\/\">frittata<\/a><\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">Non sapevo delle ottime qualita&#8217; terapeutiche dei fiori di sambuco, non per ultimo l&#8217;aiuto a drenare i liquidi (molto utile nel mio caso)<\/p>\n<p style=\"text-align: justify;\">Qui alcune info tratte da Wiki:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Viene usato come aroma nel pane per fare il &#8220;pane col sambuco&#8221;<\/li>\n<li style=\"text-align: justify;\">Con i fiori \u00c3\u00a8 possibile fare uno sciroppo, da diluire poi con acqua, ottenendo una bevanda dissetante, che \u00c3\u00a8 molto usata in Tirolo e nei paesi nordici. La si pu\u00c3\u00b2 anche far fermentare, ottenendo cos\u00c3\u00ac una specie di spumante.<br \/>\nLo sciroppo entra anche nella preparazione di cocktail, come l'&#8221;Hugo (cocktail)&#8221;<\/li>\n<li style=\"text-align: justify;\">Le bacche sono eduli solo dopo cottura e vengono impiegate per gelatine e marmellate, di cui non abusare, a causa delle propriet\u00c3\u00a0 lassative. Le bacche vengono utilizzate anche per minestre dolci, come la Fliederbeersuppe del nord della Germania.<\/li>\n<li style=\"text-align: justify;\">La pianta viene utilizzata anche a scopo ornamentale, mentre dal tronco si ricava un legno duro e compatto, utilizzato come combustibile e per lavori al tornio; il legno dei giovani rami al contrario \u00c3\u00a8 tenero e fragile e non trova applicazioni pratiche.<\/li>\n<li style=\"text-align: justify;\">Le bacche e il loro succo, fresco o fermentato, sono usati per produrre inchiostri che, a seconda della specie, delle condizioni della pianta e della ricetta, possono apparire blu, blu\/nero, marrone, lilla, rosso<\/li>\n<\/ul>\n<p>mentra altre info sono reperibili in altri links.<\/p>\n<p>&nbsp;<\/p>\n<p>Avevo pensato di utilizzare la restante parte per preparare anche uno sciroppo ma, memore dei miei fallimenti nel mantenere a lungo questi preparati sciropposi, ci ho rinunciato da subito.<\/p>\n<p>Al momento ho lavato i fiori, tentando di farli seccare per preparare in seguito un decotto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15181\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20150608_150822.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20150608_150822.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20150608_150822-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20150608_150822-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>Fiori di sambuco raccolti e posti ad asciugare<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;altra domenica da Oma ho raccolto un bel mazzo di fiori di sambuco. Ho poi scoperto che tutta la stragrande maggioranza della strada era invasa da queste piante! Ma quanto sono ignorante, spesso&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,22],"tags":[],"class_list":["post-1094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1094"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1094\/revisions"}],"predecessor-version":[{"id":41095,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1094\/revisions\/41095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15181"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}