{"id":10925,"date":"2018-04-08T11:31:50","date_gmt":"2018-04-08T10:31:50","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=10925"},"modified":"2021-02-02T08:54:19","modified_gmt":"2021-02-02T07:54:19","slug":"monaco-ammersee","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/04\/08\/monaco-ammersee\/","title":{"rendered":"Monaco: Ammersee &#038; Monastero di Andechs"},"content":{"rendered":"<p style=\"text-align: justify;\">Magari potra&#8217; sembrarvi strano, ma nei dintorni di Monaco ci sono diversi laghi, velocemente e facilmente accessibili tramite i normali mezzi di trasporto comunali (S-Bahn).<!--more--><\/p>\n<p style=\"text-align: justify;\">Qualche domenica fa, abbiamo deciso di fare una gita in uno di questi laghi, precisamente sull&#8217;Ammersee.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10966\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8431-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8431-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8431-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8431-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8431-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217; <b>Ammersee<\/b> e&#8217; considerato uno tra i piu&#8217; grandi laghi della Baviera, dopo il Chiemsee e lo Starnberger.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10926\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/index.jpg\" alt=\"\" width=\"207\" height=\"243\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/index.jpg 207w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/index-128x150.jpg 128w\" sizes=\"auto, (max-width: 207px) 100vw, 207px\" \/><\/p>\n<p style=\"text-align: justify;\">Siamo dunque arrivati ed abbiamo lasciato la nostra auto vicino a Eching, precisamente a Stegen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10967\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8446-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8446-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8446-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8446-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8446-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10968\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8449-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8449-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8449-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8449-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8449-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10969\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8453-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8453-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8453-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8453-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8453-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10970 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8454-e1524393180121-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8454-e1524393180121-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8454-e1524393180121-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8454-e1524393180121-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8454-e1524393180121-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10971 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8461-e1523986258682-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8461-e1523986258682-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8461-e1523986258682-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8461-e1523986258682-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8461-e1523986258682-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Abbiamo poi preso il traghetto che ci ha portato di qua e di la&#8217; per il lago, raggiungendo la cittadina di <strong>Herrsching<\/strong>, dopo circa un&#8217;oretta di navigazione.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10972\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8467-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8467-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8467-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8467-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8467-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10973 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8468-e1523986277155-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8468-e1523986277155-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8468-e1523986277155-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8468-e1523986277155-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8468-e1523986277155-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10974\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8470-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8470-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8470-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8470-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8470-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Visto l&#8217;orario, abbiamo deciso di fermarci subito a pranzo, prima di intrapprendere la salita verso il\u00c2\u00a0<strong> Monastero di Andechs<\/strong> .<\/p>\n<p style=\"text-align: justify;\">La sosta e&#8217; stata presso il ristorante italiano &#8221; <strong>La Dolce Vita<\/strong> &#8220;.<br \/>\nPremetto che non amo particolarmente mangiare cibo italiano in &#8220;ristoranti italiani&#8221; ma avendo gia&#8217; mangiato la pizza settimanale, ho diviso con Stephan un piatto di &#8220;pasta ai 4 formaggi&#8221; ed uno di &#8220;ravioli panna e prosciutto&#8221;, mentre Tobias si e&#8217; mangiato la sua &#8220;margherita&#8221;.<br \/>\nIl cibo non e&#8217; stato terribile come mi sarei potuta aspettare da un &#8220;ristorante italiano&#8221;.<\/p>\n<p>I ravioli li ho proprio apprezzati, spazzolando la mia porzione.<br \/>\nIl ristorante lo ho trovato nella media rispetto ad altri testati, cosi&#8217; come il prezzo non particolarmente esagerato.<\/p>\n<figure id=\"attachment_10975\" aria-describedby=\"caption-attachment-10975\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10975 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8475-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8475-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8475-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8475-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8475-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10975\" class=\"wp-caption-text\">La Dolce Vita &#8211; Ravioli Panna e Prosciutto<\/figcaption><\/figure>\n<p>Il servizio e&#8217; stato celere ed il personale cortese.<br \/>\nLa sosta sulla terrazza ci ha ritemprato abbastanza prima della passeggiata in montagna, mentre il sole ci ha accompagnati per tutta la giornata (era ora!!! da quanto non vedevamo una giornata di sole???).<\/p>\n<p>Al termine del pranzo abbiamo proseguito per il\u00c2\u00a0 <strong>Monastero di Andechs<\/strong> ed il suo <strong>Sacro Monte<\/strong>.<\/p>\n<p>Per raggiungere la cima, abbiamo seguito uno dei tanti sentieri &#8211; a piedi &#8211; a disposizione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10976\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8480-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8480-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8480-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8480-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8480-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10977\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8483-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8483-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8483-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8483-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8483-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Personalmente ero decisamente stravolta, non tanto per la difficolta&#8217; del percorso (che era veramente di bassa intensita&#8217;) quanto per la scarsa attivita&#8217; fisica che faccio quotidianamente.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10978 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8484-e1523986299100-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8484-e1523986299100-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8484-e1523986299100-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8484-e1523986299100-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8484-e1523986299100-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10979\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8485-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8485-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8485-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8485-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8485-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Il <strong>santuario di Andechs<\/strong> e&#8217; situato in posizione elevata rispetto al Lago di Ammer, ed \u00c3\u00a8 famoso nel mondo (anche, o forse??, per la sua birra).<br \/>\nAd ogni modo, ogni anno migliaia di turisti visitano il santuario e vi si ritirano per rigenerare corpo e anima.<\/p>\n<figure id=\"attachment_10980\" aria-describedby=\"caption-attachment-10980\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10980 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8498-e1523986315381-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8498-e1523986315381-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8498-e1523986315381-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8498-e1523986315381-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8498-e1523986315381-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10980\" class=\"wp-caption-text\">Il santuario di Andechs<\/figcaption><\/figure>\n<figure id=\"attachment_10981\" aria-describedby=\"caption-attachment-10981\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10981 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8503-e1523986327141-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8503-e1523986327141-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8503-e1523986327141-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8503-e1523986327141-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8503-e1523986327141-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10981\" class=\"wp-caption-text\">Il santuario di Andechs &#8211; Interno<\/figcaption><\/figure>\n<figure id=\"attachment_10982\" aria-describedby=\"caption-attachment-10982\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10982 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8507-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8507-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8507-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8507-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8507-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10982\" class=\"wp-caption-text\">Il santuario di Andechs &#8211; Interno<\/figcaption><\/figure>\n<p><em>Perche&#8217; e&#8217; famoso questo luogo?<\/em><\/p>\n<p style=\"text-align: justify;\">Dal XII secolo il \u00c2\u00abSacro Monte\u00c2\u00bb, situato sulla riva orientale del lago di Ammer e allora sede dell&#8217;omonima dinastia di conti, \u00c3\u00a8 meta di numerosi pellegrini: si tratta del pi\u00c3\u00b9 antico pellegrinaggio documentato della Baviera, ed \u00c3\u00a8 vivo ancora oggi.<br \/>\nNel X secolo il conte Rasso, leggendario avo dei conti di Diessen-Andechs, di ritorno da un pellegrinaggio in Terra Santa port\u00c3\u00b2 con s\u00c3\u00a9 al castello di Andechs delle preziose \u00c2\u00abreliquie del Signore\u00c2\u00bb.<br \/>\nA partire dal 1128 il conte Bertoldo II di Andechs obblig\u00c3\u00b2 i suoi sudditi a venerare ogni anno le reliquie qui conservate del cosiddetto \u00c2\u00ab<a https:\/\/www.andechs.de\/wallfahrt-kirche\/wallfahrt-heute\/\">Sacro Tesoro<\/a>\u00c2\u00bb.<br \/>\nUna serie di avvenimenti politici portarono al tramonto della potente dinastia dei conti di Andechs.<br \/>\nNel 1246 il castello di Andechs, compresa la sua cappella, venne distrutto e il \u00c2\u00abtesoro di reliquie\u00c2\u00bb fu considerato perduto.<\/p>\n<p style=\"text-align: justify;\">Secondo la leggenda, nel 1388 durante la celebrazione di una messa nella ex cappella del castello, un topo avrebbe riportato alla luce un pezzo di una reliquia, indizio della presenza del perduto \u00c2\u00abtesoro\u00c2\u00bb.<br \/>\nStoricamente \u00c3\u00a8 documentato il ritrovamento del \u00c2\u00abSacro Tesoro\u00c2\u00bb sotto l&#8217;altare della cappella del castello. A seguito del ritrovamento ricominci\u00c3\u00b2 il flusso dei pellegrini verso Andechs.<\/p>\n<p>Nel 1455 il duca di Wittelsbach Alberto III fond\u00c3\u00b2 il monastero benedettino di Andechs per la gestione e la custodia del \u00c2\u00abSacro Tesoro\u00c2\u00bb e per la cura dei pellegrini.<\/p>\n<figure id=\"attachment_10983\" aria-describedby=\"caption-attachment-10983\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10983 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8510-e1523986345932-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8510-e1523986345932-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8510-e1523986345932-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8510-e1523986345932-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8510-e1523986345932-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10983\" class=\"wp-caption-text\">Il santuario di Andechs &#8211; Interno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il monastero di Andechs, situato in posizione ben visibile sul <strong>Sacro Monte<\/strong>, \u00c3\u00a8 il pi\u00c3\u00b9 antico luogo di pellegrinaggio della Baviera e dal 1850 costituisce la risorsa economica dell&#8217;abbazia benedettina di San Bonifacio a Monaco.<\/p>\n<p>I benedettini gestiscono questa meta di pellegrinaggio sin dal 1455, vivendo secondo la regola di San Benedetto, espressa dalla formula \u00c2\u00abora et labora\u00c2\u00bb, ossia \u00c2\u00abprega e lavora\u00c2\u00bb. Sul Sacro Monte la comunit\u00c3\u00a0 di monaci si occupa dell&#8217;assistenza spirituale ai pellegrini, della cura parrocchiale delle comunit\u00c3\u00a0 circostanti e della gestione delle attivit\u00c3\u00a0 economiche.<\/p>\n<p>In quanto risorsa economica, il monastero di Andechs mira a conseguire (come da programma della fondazione Re Ludovico I) gli introiti necessari per il mantenimento dell&#8217;abbazia di San Bonifacio a Monaco e Andechs.<br \/>\nIl monastero non \u00c3\u00a8 beneficiario di imposte ecclesiastiche<\/p>\n<figure id=\"attachment_10984\" aria-describedby=\"caption-attachment-10984\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10984 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8512-e1523986362800-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8512-e1523986362800-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8512-e1523986362800-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8512-e1523986362800-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8512-e1523986362800-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10984\" class=\"wp-caption-text\">Il santuario di Andechs &#8211; Interno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Numerosissimi ex-voto documentano il legame del santuario e dei pellegrini con il \u00c2\u00abSacro Monte\u00c2\u00bb, come viene anche chiamata la montagna di Andechs dall&#8217;inizio del XV secolo a causa delle reliquie qui conservate.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10985\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8513-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8513-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8513-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8513-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8513-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;esterno della Chiesa, dalle linee aggraziate e semplici, contrasta con il ridondante barocco dell&#8217;interno (1712).<br \/>\nIn una cappella, a sorpresa, la tomba di Carl Orff, famoso soprattutto per i Carmina Burana.<\/p>\n<p style=\"text-align: justify;\">E&#8217; inoltre possibile salire sulla torre, oltre le campane, e godere del panorama che arriva sino al lago.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10986\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8519-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8519-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8519-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8519-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8519-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10987 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8526-e1523986378441-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8526-e1523986378441-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8526-e1523986378441-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8526-e1523986378441-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8526-e1523986378441-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Poco sotto la chiesa, il negozio del monastero offre numerosi oggetti d&#8217;arte sacra, tradizionali lavori in cera e libri sul pellegrinaggio<\/p>\n<p style=\"text-align: justify;\">Come scrivevo, il Monastero non ha introiti se non quelli guadagnati da loro.<br \/>\nOttima (e famosa) la loro birra, venduta anche qui.<br \/>\nA disposizione, inoltre, anche un grande BierGarten dove e&#8217; possibile mangiare il cibo portato da casa (o acquistato in loco), annaffiato della birra locale.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10928 aligncenter\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/birra.jpg\" alt=\"\" width=\"178\" height=\"283\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/birra.jpg 178w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/birra-94x150.jpg 94w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><br \/>\nDi ritorno al porticciolo, ci siamo fatti un gelato al ritorno, presso l&#8217;Eiscafe&#8217; Riva&#8230;<\/p>\n<p>Decisamente una gita all&#8217;insegna della vita fuori di casa.<br \/>\nSe passate da queste parti, ve la consiglio !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10988\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8536-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8536-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8536-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8536-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8536-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10989 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8544-e1523986397881-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8544-e1523986397881-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8544-e1523986397881-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8544-e1523986397881-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8544-e1523986397881-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10990\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8552-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8552-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8552-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8552-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8552-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10991 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8555-e1523986418532-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8555-e1523986418532-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8555-e1523986418532-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8555-e1523986418532-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/04\/IMG_8555-e1523986418532-768x1364.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Per Informazioni<\/strong><\/p>\n<p>La Dolce Vita<br \/>\nSeestr. 52,<br \/>\n82211 Herrsching am Ammersee<\/p>\n<p>Eiscafe Riva<br \/>\nSeestr. 50,<br \/>\n82211 Herrsching am Ammersee<\/p>\n<p>http:\/\/www.andechs.de\/<br \/>\nBergstr. 2,<br \/>\n82346 Andechs<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magari potra&#8217; sembrarvi strano, ma nei dintorni di Monaco ci sono diversi laghi, velocemente e facilmente accessibili tramite i normali mezzi di trasporto comunali (S-Bahn).<\/p>\n","protected":false},"author":2,"featured_media":10974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162,163,110],"tags":[26,28],"class_list":["post-10925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dintorni","category-dove-mangiare","category-monaco","tag-da_fare","tag-dove_mangiare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/10925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=10925"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/10925\/revisions"}],"predecessor-version":[{"id":28448,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/10925\/revisions\/28448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10974"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=10925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=10925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=10925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}