{"id":1063,"date":"2015-07-22T18:39:41","date_gmt":"2015-07-22T17:39:41","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/crema-al-cucchiaio-di-gaia\/"},"modified":"2019-04-25T19:00:58","modified_gmt":"2019-04-25T18:00:58","slug":"crema-al-cucchiaio-di-gaia","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/07\/22\/crema-al-cucchiaio-di-gaia\/","title":{"rendered":"Crema al cucchiaio &#8211; di Gaia"},"content":{"rendered":"<p style=\"text-align: justify;\">Mentre cercavo la ricetta delle &#8220;Lingua della Suocera&#8221; per utilizzare un po&#8217; di licoli in esubero, mi sono imbattuta in <a href=\"http:\/\/ilgaiomondodigaia.blogspot.co.uk\/2015\/06\/dessert-al-cucchiaio.html\" target=\"_blank\" rel=\"noopener\">codesto<\/a> dolcetto.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Detto fatto, subito preparato.<\/p>\n<p>La preparazione e&#8217; veramente semplice, giusto 10 minuti&#8230;<\/p>\n<p>Ecco la &#8220;versione originale&#8221;, tratta dal link riportato precedentemente<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong>:<\/p>\n<pre>200 gr di latte di mandorla (o vaccino) (vi consiglio vivamente di usare latte di mandorla per la deliziosa unione con la fragola)\r\n 200 gr di fragole (pesate senza il picciolo)\r\n 45 gr di frumina\r\n 2 cucchiaini rasi di zucchero di canna (regolatevi secondo i vostri gusti e in base al punto di dolcezza della frutta)\r\n granella di pistacchio (abbondante!)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate le fragole, privatele\u00c2\u00a0 del picciolo e tamponatele con della carta assorbente.<\/p>\n<p style=\"text-align: justify;\">Versate il latte nel boccale del frullatore, aggiungete le fragole a tocchetti e lo zucchero, frullate ben benino.<\/p>\n<p style=\"text-align: justify;\">In un pentolino, che contenga poi tutta la quantit\u00c3\u00a0 del frullato, diluite un p\u00c3\u00b2 di quest&#8217;ultimo con la frumina aggiunta poco per volta, versate la restante parte del frullato, mescolate con un cucchiaio, ponete su fornello piccolo al minimo e girate ininterrottamente con una frusta a mano per circa 15 minuti, tempo in cui si sar\u00c3\u00a0 addensato il contenuto che dovr\u00c3\u00a0 risultare come una crema un bel p\u00c3\u00b2 consistene.<\/p>\n<p style=\"text-align: justify;\">Trasferite, con un cucchiaio, in bicchieri a calice per una tavola chic o simpatici stampini per una occasione pi\u00c3\u00b9 sfiziosa e meno impegnativa.<\/p>\n<p style=\"text-align: justify;\">Note:<br \/>\n-Se gustata come dessert: lasciate raffreddare a temperatura ambiente, ponete in frigo per 5 ore, servite con granella di pistacchio ed una fragola per ogni bicchiere.<br \/>\n-Se impiegata come farcia: saltate il passaggio in frigo.<\/p>\n<figure id=\"attachment_5811\" aria-describedby=\"caption-attachment-5811\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5811\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/07\/IMG_20150709_171537-1-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/07\/IMG_20150709_171537-1-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/07\/IMG_20150709_171537-1-225x300.jpg 225w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2015\/07\/IMG_20150709_171537-1.jpg 1200w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-5811\" class=\"wp-caption-text\">Crema al cucchiaio<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Personalmente ho usato delle banane non pensando, poi, al terribile cambio di colore, tendente al marroncino..<br \/>\nInvece della granella, ho messo della cannella in polvere, limitando i danni per la dieta.<\/p>\n<p style=\"text-align: justify;\">Nella ricetta otiginale, era richiesta la FRUMINA.<br \/>\nNon avendola ho aggiunto un &#8216;semolino&#8217;, ma la prossima volta tentero&#8217; con la fecola o con la farina di carrube (cosi&#8217; facendo il composto dovrebbe risultare piu&#8217; cremoso e leggermente meno &#8220;grumoso&#8221;).<\/p>\n<p style=\"text-align: justify;\">Nel mio caso ho preparato 3 porzioni, pur mantenendo le stesse quantita&#8217; descritte nella ricetta.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Un po\u00e2\u20ac\u2122 di calcoli ProPoints:<\/span><\/p>\n<p style=\"text-align: justify;\">2.5 pp &#8211; 200 gr di latte di mandorla (o vaccino)<br \/>\n0 pp &#8211; 200 gr di fragole \/ banane \/ frutta<br \/>\n4 pp &#8211; 45 gr di frumina<br \/>\n2 pp &#8211; 2 cucchiaini rasi di zucchero di canna<br \/>\n0 pp &#8211; cannella<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">8.5 pp in totale\u00c2\u00a0\u00c2\u00a0 =&gt;\u00c2\u00a0 2.8\u00c2\u00a0 (per 1 porzione \u00e2\u20ac\u201c di 4)<\/span><\/p>\n<p style=\"text-align: justify;\">Logicamente, se volete &#8216;coprire&#8217; con pistacchi, amaretti sbriciolati, etc.. bisogna addizionare tali valori.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre cercavo la ricetta delle &#8220;Lingua della Suocera&#8221; per utilizzare un po&#8217; di licoli in esubero, mi sono imbattuta in codesto dolcetto.<\/p>\n","protected":false},"author":2,"featured_media":5811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[107,49],"class_list":["post-1063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-dessert","category-food","tag-frutta","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"predecessor-version":[{"id":16649,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1063\/revisions\/16649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/5811"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}