{"id":1003,"date":"2015-11-11T18:39:39","date_gmt":"2015-11-11T17:39:39","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/san-martin-2015\/"},"modified":"2018-11-06T20:20:11","modified_gmt":"2018-11-06T19:20:11","slug":"san-martin-2015","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/11\/11\/san-martin-2015\/","title":{"rendered":"San Martin &#8211; 2015"},"content":{"rendered":"<p style=\"text-align: justify;\">Anche quest&#8217;anno (come in alcune dei post precedenti <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/11\/11\/san-martin-2009\/\">2009<\/a>, <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/11\/san-martin-2013\/\" target=\"_blank\" rel=\"noopener\">2013<\/a>, <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2014\/11\/11\/san-martino-2014\/\" target=\"_blank\" rel=\"noopener\">2014<\/a>) abbiamo preparato i nostri biscotti<!--more--><\/p>\n<p style=\"text-align: justify;\">per festeggiare San Martin.<\/p>\n<p style=\"text-align: justify;\">L&#8217;impasto non l&#8217;ho mischiato io, per ragioni di tempo, ma mi sono fatta aiutare da &#8220;Tante Fanny&#8221;.<\/p>\n<figure id=\"attachment_7654\" aria-describedby=\"caption-attachment-7654\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7654\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_164040-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7654\" class=\"wp-caption-text\">&#8220;Tante Fanny&#8221; ci ha aiutato<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La forma e&#8217; la solita, di oca, la stessa usata anche l&#8217;anno scorso.<br \/>\nCon la modifica della &#8220;personalizzazione&#8221;&#8230;<\/p>\n<figure id=\"attachment_7653\" aria-describedby=\"caption-attachment-7653\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7653\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171111-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7653\" class=\"wp-caption-text\">Le nostre &#8220;oche&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il ragazzo?<\/p>\n<p style=\"text-align: justify;\">Si e&#8217; spazzolato letteralmente i suoi, e lo stesso il suo amico Yannick.<\/p>\n<figure id=\"attachment_7652\" aria-describedby=\"caption-attachment-7652\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7652\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151105_171129-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7652\" class=\"wp-caption-text\">La personalizzazione un po&#8217; sbiadita, ma presente<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E qui, non lo nascondo, mi sono fatta aiutare da loro due, giusto per passare un po&#8217; di tempo insieme\u00c2\u00a0 \ud83d\ude42<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno (come in alcune dei post precedenti 2009, 2013, 2014) abbiamo preparato i nostri biscotti<\/p>\n","protected":false},"author":2,"featured_media":7652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-1003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1003"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1003\/revisions"}],"predecessor-version":[{"id":13407,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1003\/revisions\/13407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7652"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}